{"id":5229656,"date":"2022-08-01T18:48:44","date_gmt":"2022-08-01T16:48:44","guid":{"rendered":"https:\/\/www.ozono21.com\/blog\/?p=5229656"},"modified":"2026-02-15T21:12:20","modified_gmt":"2026-02-15T19:12:20","slug":"formaldehido-y-mercurio-llenan-nuestra-casa","status":"publish","type":"post","link":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/","title":{"rendered":"FORMALDEHIDO y MERCURIO llenan nuestra CASA"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" style=\"MARGIN: 20px 0px 0px 20px;  border: 0px;\"  src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2016\/06\/Habitaciones-de-los-hoteles-300x229.jpg\" alt=\"FORMALDEHIDO y MERCURIO\" width=\"300\" height=\"229\" class=\"alignright size-medium wp-image-5217885\" title=\"FORMALDEHIDO y MERCURIO llenan nuestras CASA\" srcset=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2016\/06\/Habitaciones-de-los-hoteles-300x229.jpg 300w, https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2016\/06\/Habitaciones-de-los-hoteles.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Nuestros hogares est\u00e1n atiborrados de FORMALDEHIDO Y MERCURIO<\/p>\n<p><a title=\"AIRE PURIFICADO necesario el OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/aire-purificado-necesario-ozono\/615\/\"  rel=\"noopener noreferrer\">Un equipo de investigadores de la Washington State University (Estados Unidos) ha encontrado niveles \u00absorprendentemente altos\u00bb de contaminantes, entre ellos FORMALDEHIDO y MERCURIO, en hogares cuidadosamente monitoreados<\/p>\n<p><a title=\"Generadores de Ozono21\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/maquina-ozono-necesario-tu-hogar\/576\/\"  rel=\"noopener noreferrer\">La contaminaci\u00f3n del aire, ya sea dentro o fuera de un edificio, tiene un impacto significativo en la salud de las personas, incluyendo su coraz\u00f3n, pulmones, cerebro y salud neurol\u00f3gica.<\/a><\/h2>\n<\/p>\n<p style=\"text-align: justify;\">Pero, mientras que ha ido aumentando la regulaci\u00f3n de la contaminaci\u00f3n del aire exterior en los \u00faltimos 40 a\u00f1os, <strong>existe \u00abpoca regulaci\u00f3n\u00bb del aire en los hogares de las personas<\/strong>, lamentan los cient\u00edficos.<\/p>\n<p style=\"text-align: justify;\">Las leyes de construcci\u00f3n generalmente requieren que las casas sean estructuralmente s\u00f3lidas y que las personas se sientan c\u00f3modas, con un impacto m\u00ednimo de <strong>los olores y la humedad<\/strong>.<\/p>\n<p><p style=\"text-align: justify;\"><strong>La gente piensa que la contaminaci\u00f3n del aire es un problema al aire libre, pero no reconocen que se est\u00e1n exponiendo a tasas de emisi\u00f3n mucho m\u00e1s altas dentro de sus hogares<\/strong>, comenta Tom Jobson, autor principal del trabajo, publicado en la revista &#8216;Building and Environment&#8217;.<\/p>\n<p style=\"text-align: justify;\">Estas emisiones provienen de una variedad de fuentes, tales como materiales de <strong>construcci\u00f3n, muebles, productos qu\u00edmicos<\/strong> para el hogar y de actividades de la gente como <strong>cocinar<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Una de las maneras de eliminar los productos qu\u00edmicos nocivos es con <strong>ventilaci\u00f3n hacia el exterior<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Pero, con <strong><a title=\"OZONO bueno con el medioambiente y en la desinfecci\u00f3n\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/ozono-bueno-medioambiente-desinfeccion\/211\/\"  rel=\"noopener noreferrer\">la creciente preocupaci\u00f3n por el cambio clim\u00e1tico y el inter\u00e9s en reducir el uso de energ\u00eda, los constructores est\u00e1n tratando de hacer que las casas sean m\u00e1s herm\u00e9ticas, lo que podr\u00eda estar empeorando el problema sin darse cuenta<\/a><\/strong>.<\/p>\n<p style=\"text-align: justify;\">En su estudio, los investigadores observaron una variedad de hogares, con el fin de reflejar los estilos de vivienda t\u00edpicos y la edad en Estados Unidos.<\/p>\n<p style=\"text-align: justify;\">As\u00ed, encontraron que los niveles de FORMALDEHIDO y MERCURIO se elevaban en los hogares a medida que aumentaban las temperaturas en el interior, entre tres y cinco partes por bill\u00f3n cada vez que la temperatura aumentaba un grado Celsius.<\/p>\n<p style=\"text-align: justify;\"><strong>El trabajo muestra c\u00f3mo las olas de calor y el cambio clim\u00e1tico regional podr\u00edan afectar la calidad del aire interior en el futuro.<\/strong><\/p>\n<p style=\"text-align: justify;\">A medida que la casa se calienta, hay mucho m\u00e1s FORMALDEHIDO y MERCURIO en la casa.<\/p>\n<p style=\"text-align: justify;\">Los materiales son m\u00e1s calientes y emiten gases a mayor velocidad.<\/p>\n<p style=\"text-align: justify;\"><strong>A medida que la gente pasa un verano caluroso sin aire acondicionado, va a estar expuesta a concentraciones mucho m\u00e1s altas de contaminantes en su interior.<\/strong><\/p>\n<p style=\"text-align: justify;\">Las leyes de construcci\u00f3n generalmente requieren que las casas sean estructuralmente s\u00f3lidas y que las personas se sientan c\u00f3modas, con un impacto m\u00ednimo de los olores y la humedad.<\/p>\n<p style=\"text-align: justify;\">Los investigadores tambi\u00e9n han evidenciado que los niveles de contaminaci\u00f3n variaban a lo largo del d\u00eda: eran m\u00e1s altos en la tarde y m\u00e1s bajos en la madrugada.<\/p>\n<p style=\"text-align: justify;\"><strong>Hasta ahora, los fabricantes y constructores han asumido que los contaminantes permanecen iguales durante todo el d\u00eda mientras consideran las emisiones de sus materiales, por lo que tal vez no tengan una idea real de cu\u00e1nta contaminaci\u00f3n est\u00e1 expuesta la gente en interiores.<\/strong><\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Actualidad ACCION del OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/accion-del-ozono\/423\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Noticias-Relacionadas.png\" alt=\"Noticias Relacionadas\" width=\"600\" height=\"25\" border=\"0\" \/><\/a><\/strong>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><big><strong><\/p>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td height=\"150\" width=\"250\" ><a title=\"POST sobre CALIDAD del AIRE\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/blog\/?s=CALIDAD+del+AIRE\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS-300x180.png\" alt=\"FORMALDEHIDO y MERCURIO\" width=\"150\" height=\"150\"  style=\"margin: 10px 10px 0px 50px; cursor: hand; border: 0px;\" \/><\/a><\/td>\n<td height=\"150\" width=\"350\" style=\"text-align: left; vertical-align: middle;\"><strong><a title=\"POST sobre CALIDAD del AIRE\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/blog\/?s=CALIDAD+del+AIRE\" rel=\"noopener noreferrer\">POST sobre CALIDAD del AIRE<\/a><\/strong><\/td>\n<\/tr>\n<tr>\n<td height=\"150\" width=\"250\" ><a title=\"GENERADORES de OZONO DESINFECCION y limpieza\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/generadores-ozono-desinfeccion-limpieza\/565\/\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/imagenes\/actualidad\/generadores_ozono_desinfeccion_limpieza_1608155726.jpg\" alt=\"FORMALDEHIDO y MERCURIO\" width=\"150\" height=\"150\"  style=\"margin: 10px 10px 0px 50px; cursor: hand; border: 0px;\" \/><\/a><\/td>\n<td height=\"150\" width=\"350\" style=\"text-align: left; vertical-align: middle;\"><strong><a title=\"GENERADORES de OZONO DESINFECCION y limpieza\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/generadores-ozono-desinfeccion-limpieza\/565\/\" rel=\"noopener noreferrer\">GENERADORES de OZONO DESINFECCION y limpieza<\/a><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/strong><\/big><\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Videos YouTube\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/user\/ozono21\/videos?sort=p&amp;view=0&amp;flow=grid\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Videos-Youtube.png\" alt=\"Videos Youtube\" width=\"600\" height=\"25\" border=\"0\" \/><\/a><\/strong>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: center\"><iframe loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/Lcv2xcWmsMU\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: center\"><iframe loading=\"lazy\" width=\"853\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/wsw8CRcwDBc?list=PLRh6zoWeBO16xveA32v53lRJfE81gLUqF\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5229656\" class=\"pvc_stats total_only  \" data-element-id=\"5229656\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Nuestros hogares est\u00e1n atiborrados de FORMALDEHIDO Y MERCURIO Un equipo de investigadores de la Washington State University (Estados Unidos) ha encontrado niveles \u00absorprendentemente altos\u00bb de contaminantes, entre ellos FORMALDEHIDO y MERCURIO, en hogares cuidadosamente monitoreados La contaminaci\u00f3n del aire, ya &hellip; <a href=\"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5229656\" class=\"pvc_stats total_only  \" data-element-id=\"5229656\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":46969,"featured_media":5205410,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,48,4],"tags":[21,81,36],"class_list":["post-5229656","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","category-sociedad","category-toxinas","tag-salud-2","tag-sociedad","tag-toxinas-2"],"a3_pvc":{"activated":true,"total_views":5254,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FORMALDEHIDO y MERCURIO llenan la CASA<\/title>\n<meta name=\"description\" content=\"FORMALDEHIDO y MERCURIO llenan nuestras CASA. La Washington State University ha encontrado niveles altos de contaminantes, en nuestros hogares\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FORMALDEHIDO y MERCURIO llenan la CASA\" \/>\n<meta property=\"og:description\" content=\"FORMALDEHIDO y MERCURIO llenan nuestras CASA. La Washington State University ha encontrado niveles altos de contaminantes, en nuestros hogares\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"- Blog Ozono21\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-01T16:48:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-15T19:12:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"959\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"INVESTIGACION Ozono21\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"INVESTIGACION Ozono21\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/formaldehido-y-mercurio-llenan-nuestra-casa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/formaldehido-y-mercurio-llenan-nuestra-casa\\\/\"},\"author\":{\"name\":\"INVESTIGACION Ozono21\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/09b7d3e74b7c4469cd705f2b20bca17c\"},\"headline\":\"FORMALDEHIDO y MERCURIO llenan nuestra CASA\",\"datePublished\":\"2022-08-01T16:48:44+00:00\",\"dateModified\":\"2026-02-15T19:12:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/formaldehido-y-mercurio-llenan-nuestra-casa\\\/\"},\"wordCount\":564,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/formaldehido-y-mercurio-llenan-nuestra-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif\",\"keywords\":[\"Salud\",\"Sociedad\",\"Toxinas\"],\"articleSection\":[\"Salud\",\"Sociedad\",\"Toxinas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/formaldehido-y-mercurio-llenan-nuestra-casa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/formaldehido-y-mercurio-llenan-nuestra-casa\\\/\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/formaldehido-y-mercurio-llenan-nuestra-casa\\\/\",\"name\":\"FORMALDEHIDO y MERCURIO llenan la CASA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/formaldehido-y-mercurio-llenan-nuestra-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/formaldehido-y-mercurio-llenan-nuestra-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif\",\"datePublished\":\"2022-08-01T16:48:44+00:00\",\"dateModified\":\"2026-02-15T19:12:20+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/09b7d3e74b7c4469cd705f2b20bca17c\"},\"description\":\"FORMALDEHIDO y MERCURIO llenan nuestras CASA. La Washington State University ha encontrado niveles altos de contaminantes, en nuestros hogares\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/formaldehido-y-mercurio-llenan-nuestra-casa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/formaldehido-y-mercurio-llenan-nuestra-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/formaldehido-y-mercurio-llenan-nuestra-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif\",\"contentUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif\",\"width\":959,\"height\":719},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/formaldehido-y-mercurio-llenan-nuestra-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FORMALDEHIDO y MERCURIO llenan nuestra CASA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\",\"name\":\"Blog Ozono21\",\"description\":\" - Blog Ozono21\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/09b7d3e74b7c4469cd705f2b20bca17c\",\"name\":\"INVESTIGACION Ozono21\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g\",\"caption\":\"INVESTIGACION Ozono21\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FORMALDEHIDO y MERCURIO llenan la CASA","description":"FORMALDEHIDO y MERCURIO llenan nuestras CASA. La Washington State University ha encontrado niveles altos de contaminantes, en nuestros hogares","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/","og_locale":"es_ES","og_type":"article","og_title":"FORMALDEHIDO y MERCURIO llenan la CASA","og_description":"FORMALDEHIDO y MERCURIO llenan nuestras CASA. La Washington State University ha encontrado niveles altos de contaminantes, en nuestros hogares","og_url":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/","og_site_name":"- Blog Ozono21","article_published_time":"2022-08-01T16:48:44+00:00","article_modified_time":"2026-02-15T19:12:20+00:00","og_image":[{"width":959,"height":719,"url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif","type":"image\/gif"}],"author":"INVESTIGACION Ozono21","twitter_misc":{"Escrito por":"INVESTIGACION Ozono21","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/#article","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/"},"author":{"name":"INVESTIGACION Ozono21","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/09b7d3e74b7c4469cd705f2b20bca17c"},"headline":"FORMALDEHIDO y MERCURIO llenan nuestra CASA","datePublished":"2022-08-01T16:48:44+00:00","dateModified":"2026-02-15T19:12:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/"},"wordCount":564,"commentCount":0,"image":{"@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif","keywords":["Salud","Sociedad","Toxinas"],"articleSection":["Salud","Sociedad","Toxinas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/","url":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/","name":"FORMALDEHIDO y MERCURIO llenan la CASA","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/#primaryimage"},"image":{"@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif","datePublished":"2022-08-01T16:48:44+00:00","dateModified":"2026-02-15T19:12:20+00:00","author":{"@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/09b7d3e74b7c4469cd705f2b20bca17c"},"description":"FORMALDEHIDO y MERCURIO llenan nuestras CASA. La Washington State University ha encontrado niveles altos de contaminantes, en nuestros hogares","breadcrumb":{"@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/#primaryimage","url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif","contentUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif","width":959,"height":719},{"@type":"BreadcrumbList","@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/formaldehido-y-mercurio-llenan-nuestra-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ozono21.com\/blog\/"},{"@type":"ListItem","position":2,"name":"FORMALDEHIDO y MERCURIO llenan nuestra CASA"}]},{"@type":"WebSite","@id":"https:\/\/www.ozono21.com\/blog\/#website","url":"https:\/\/www.ozono21.com\/blog\/","name":"Blog Ozono21","description":" - Blog Ozono21","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ozono21.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/09b7d3e74b7c4469cd705f2b20bca17c","name":"INVESTIGACION Ozono21","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g","caption":"INVESTIGACION Ozono21"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5229656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/users\/46969"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/comments?post=5229656"}],"version-history":[{"count":0,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5229656\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media\/5205410"}],"wp:attachment":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media?parent=5229656"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/categories?post=5229656"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/tags?post=5229656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}