{"id":5226976,"date":"2021-05-02T13:21:57","date_gmt":"2021-05-02T11:21:57","guid":{"rendered":"https:\/\/www.ozono21.com\/blog\/?p=5226976"},"modified":"2026-02-22T19:57:50","modified_gmt":"2026-02-22T17:57:50","slug":"ignorancia-de-algunas-autoridades-sanitarias","status":"publish","type":"post","link":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/","title":{"rendered":"IGNORANCIA de algunas AUTORIDADES SANITARIAS"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" style=\"MARGIN: 20px 10px 20px 0px; border: 0px;\"  src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS-300x180.png\" alt=\"IGNORANCIA\" width=\"300\" height=\"180\" class=\"alignleft size-medium wp-image-5225417\" title=\"IGNORANCIA de algunas AUTORIDADES SANITARIAS\" srcset=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS-300x180.png 300w, https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Cuanta IGNORANCIA est\u00e1n demostrando algunas autoridades sanitarias<\/p>\n<p><a title=\"COMBATIR ENFERMEDADES con OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/combatir-enfermedades-ozono\/429\/\"  rel=\"noopener noreferrer\">El Doctor Jes\u00fas P\u00e9rez Pago de las tierras del Ebro aplica la ozonoterapia para curar el Covid-19, y no le importa lo que diga la administraci\u00f3n; dice, \u201cmi obligaci\u00f3n es salvar vidas\u201d<\/a><\/h2>\n<\/p>\n<p style=\"text-align: justify;\">Fuente: ITEL<\/p>\n<p style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\"><a title=\"COMBATIR ENFERMEDADES con OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/combatir-enfermedades-ozono\/429\/\" target=\"_blank\" rel=\"noopener noreferrer\">En ITEL disponemos de amplia informaci\u00f3n cient\u00edfica sobre la ozonoterapia, aunque hemos de confesar que no somos m\u00e9dicos.<\/a><\/h2>\n<\/p>\n<p style=\"text-align: justify;\">La <strong>administraci\u00f3n sanitaria sigue aconsejando la lej\u00eda<\/strong> y adem\u00e1s le pone marca \u201cEl Conejo\u201d.<\/p>\n<p style=\"text-align: justify;\">La <strong>lej\u00eda est\u00e1 prohibida en varios pa\u00edses europeos<\/strong>, algunos desde hace 21 a\u00f1os.<\/p>\n<p style=\"text-align: justify;\"><strong>La lej\u00eda no es fiable para desinfectar<\/strong> si no medimos el cloro activo en el momento del uso, ya que al ser tan inestable no podemos garantizar la desinfecci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><strong>Ejemplo:<\/strong> el transportista que trasladaba en su furgoneta esta lej\u00eda a nuestro centro de trabajo se par\u00f3 a almorzar y dej\u00f3 la furgoneta al sol, lo que nos ha llegado es un l\u00edquido con olor y color a lej\u00eda, pero cuando abrimos el envase sale un gas que es el cloro: resultado, desinfecci\u00f3n nula.<\/p>\n<p style=\"text-align: justify;\"><big><strong>La lej\u00eda es terat\u00f3gena, produce asma a sus usuarios, es cancer\u00edgena, forma cloraminas, que tambi\u00e9n son cancer\u00edgenas y afecta perjudicando el sistema reproductivo humano, entre otros muchos perjuicios.<\/strong><\/big><\/p>\n<p style=\"text-align: justify;\">En nuestro pa\u00eds hemos visto <strong>la unidad militar desinfectando aeropuertos<\/strong> y todos hemos pensado que est\u00e1bamos frente a <strong>una operaci\u00f3n de marketing, ya que muchos desconocen el efecto nocivo de la lej\u00eda<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Pero lo que es peor hemos visto <strong>desinfectar geri\u00e1tricos<\/strong>, nos parece sino una inmoralidad, <strong>s\u00ed una excesiva IGNORANCIA<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Pero <strong>no solo las administraciones est\u00e1n jugando irresponsablemente con el Covid-19<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Son muchas las empresas<\/strong>, no todas, pero demasiadas, que despu\u00e9s de pedir a ITEL la redacci\u00f3n de protocolos de desinfecci\u00f3n alardean de sus 34 p\u00e1ginas que aplican para dar seguridad al hu\u00e9sped (este ejemplo es de un hotel internacional con central en Espa\u00f1a) y vemos que el hotel se est\u00e1 limpiando con un mocho y escoba.<\/p>\n<p style=\"text-align: justify;\">Podr\u00edamos poner <strong>centenares de ejemplos<\/strong>, pondremos solo uno m\u00e1s.<\/p>\n<p style=\"text-align: justify;\">La <strong>Liga de futbol<\/strong>, con sus protocolos que desde ITEL consideramos impecables y todo termina como una herramienta de publicidad, porque vemos la UME pulverizando por todas las dependencias de los 42 clubs de futbol que forman parte de su organizaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Despu\u00e9s la administraci\u00f3n y las empresas se sorprenden de los rebrotes.<\/p>\n<p style=\"text-align: justify;\"><big><strong><marquee>\u00bf Por qu\u00e9 tanta irresponsabilidad e IGNORANCIA ?<\/marquee><\/strong><\/big><\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Actualidad ACCION del OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/accion-del-ozono\/423\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Noticias-Relacionadas.png\" alt=\"Noticias Relacionadas\" width=\"600\" height=\"25\" style=\"margin: 0px 0px 0px 0px; cursor: hand; border: 0px;\"><\/a><\/strong>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<ul><big><strong><\/p>\n<li><a title=\"AGUA con OZONO contra la INFECCI\u00f3N del VIRUS CORONA\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/\"  rel=\"noopener noreferrer\">AGUA con OZONO contra la INFECCI\u00f3N del VIRUS CORONA<\/a><\/li>\n<li><a title=\"OZONOTERAPIA contra CORONAVIRUS\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/blog\/virus\/ozonoterapia-contra-coronavirus\/\"  rel=\"noopener noreferrer\">OZONOTERAPIA contra CORONAVIRUS<\/a><\/li>\n<li><a title=\"DESINFECTANTE m\u00e1s potente contra el CORONAVIRUS es el OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/blog\/virus\/desinfectante-mas-potente-coronavirus-ozono\/\"  rel=\"noopener noreferrer\">DESINFECTANTE m\u00e1s potente contra el CORONAVIRUS es el OZONO<\/a><\/li>\n<li><a title=\"Eficaz el OZONO para MATAR el coronavirus COVID-19\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/blog\/virus\/eficaz-el-ozono-para-matar-coronavirus_covid-19\/\"  rel=\"noopener noreferrer\">Eficaz el OZONO para MATAR el coronavirus COVID-19<\/a><\/li>\n<li><a title=\"CORONAVIRUS muerto GRACIAS a el OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/coronavirus-muerto-gracias-ozono\/555\/\"  rel=\"noopener noreferrer\">CORONAVIRUS muerto GRACIAS a el OZONO<\/a><\/li>\n<li><a title=\"OZONO para desinfectar y luchar contra el CORONAVIRUS\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/ozono-para-desinfectar-luchar-contra-coronavirus\/554\/\"  rel=\"noopener noreferrer\">OZONO para desinfectar y luchar contra el CORONAVIRUS<\/a><\/li>\n<p><\/strong><\/big>\n<\/ul>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td width=\"600\" height=\"25\" align=\"center\" bgcolor=\"#3b7cff\"><strong><a title=\"Videos YouTube\" target=\"_blank\" href=\"http:\/\/www.youtube.com\/user\/ozono21\/videos?sort=p&amp;view=0&amp;flow=grid\"  rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"25\" alt=\"Videos Youtube\" border=\"0\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Videos-Youtube.png\" \/><\/a><\/strong> <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" width=\"853\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/wsw8CRcwDBc\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/Lcv2xcWmsMU\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5226976\" class=\"pvc_stats total_only  \" data-element-id=\"5226976\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Cuanta IGNORANCIA est\u00e1n demostrando algunas autoridades sanitarias El Doctor Jes\u00fas P\u00e9rez Pago de las tierras del Ebro aplica la ozonoterapia para curar el Covid-19, y no le importa lo que diga la administraci\u00f3n; dice, \u201cmi obligaci\u00f3n es salvar vidas\u201d Fuente: &hellip; <a href=\"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5226976\" class=\"pvc_stats total_only  \" data-element-id=\"5226976\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":46969,"featured_media":5225417,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7,48,4,15],"tags":[21,81,36,29],"class_list":["post-5226976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","category-sociedad","category-toxinas","category-virus","tag-salud-2","tag-sociedad","tag-toxinas-2","tag-virus-2"],"a3_pvc":{"activated":true,"total_views":3564,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IGNORANCIA de AUTORIDADES SANITARIAS<\/title>\n<meta name=\"description\" content=\"IGNORANCIA de algunas AUTORIDADES SANITARIAS La ozonoterapia para curar el Covid-19 y no le importa lo que diga la administraci\u00f3n\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IGNORANCIA de AUTORIDADES SANITARIAS\" \/>\n<meta property=\"og:description\" content=\"IGNORANCIA de algunas AUTORIDADES SANITARIAS La ozonoterapia para curar el Covid-19 y no le importa lo que diga la administraci\u00f3n\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/\" \/>\n<meta property=\"og:site_name\" content=\"- Blog Ozono21\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-02T11:21:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-22T17:57:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"INVESTIGACION Ozono21\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"INVESTIGACION Ozono21\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/sociedad\\\/ignorancia-de-algunas-autoridades-sanitarias\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/sociedad\\\/ignorancia-de-algunas-autoridades-sanitarias\\\/\"},\"author\":{\"name\":\"INVESTIGACION Ozono21\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/09b7d3e74b7c4469cd705f2b20bca17c\"},\"headline\":\"IGNORANCIA de algunas AUTORIDADES SANITARIAS\",\"datePublished\":\"2021-05-02T11:21:57+00:00\",\"dateModified\":\"2026-02-22T17:57:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/sociedad\\\/ignorancia-de-algunas-autoridades-sanitarias\\\/\"},\"wordCount\":472,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/sociedad\\\/ignorancia-de-algunas-autoridades-sanitarias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CORONAVIRUS.png\",\"keywords\":[\"Salud\",\"Sociedad\",\"Toxinas\",\"Virus\"],\"articleSection\":[\"Salud\",\"Sociedad\",\"Toxinas\",\"Virus\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/sociedad\\\/ignorancia-de-algunas-autoridades-sanitarias\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/sociedad\\\/ignorancia-de-algunas-autoridades-sanitarias\\\/\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/sociedad\\\/ignorancia-de-algunas-autoridades-sanitarias\\\/\",\"name\":\"IGNORANCIA de AUTORIDADES SANITARIAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/sociedad\\\/ignorancia-de-algunas-autoridades-sanitarias\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/sociedad\\\/ignorancia-de-algunas-autoridades-sanitarias\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CORONAVIRUS.png\",\"datePublished\":\"2021-05-02T11:21:57+00:00\",\"dateModified\":\"2026-02-22T17:57:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/09b7d3e74b7c4469cd705f2b20bca17c\"},\"description\":\"IGNORANCIA de algunas AUTORIDADES SANITARIAS La ozonoterapia para curar el Covid-19 y no le importa lo que diga la administraci\u00f3n\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/sociedad\\\/ignorancia-de-algunas-autoridades-sanitarias\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/sociedad\\\/ignorancia-de-algunas-autoridades-sanitarias\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/sociedad\\\/ignorancia-de-algunas-autoridades-sanitarias\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CORONAVIRUS.png\",\"contentUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CORONAVIRUS.png\",\"width\":600,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/sociedad\\\/ignorancia-de-algunas-autoridades-sanitarias\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IGNORANCIA de algunas AUTORIDADES SANITARIAS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\",\"name\":\"Blog Ozono21\",\"description\":\" - Blog Ozono21\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/09b7d3e74b7c4469cd705f2b20bca17c\",\"name\":\"INVESTIGACION Ozono21\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g\",\"caption\":\"INVESTIGACION Ozono21\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IGNORANCIA de AUTORIDADES SANITARIAS","description":"IGNORANCIA de algunas AUTORIDADES SANITARIAS La ozonoterapia para curar el Covid-19 y no le importa lo que diga la administraci\u00f3n","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/","og_locale":"es_ES","og_type":"article","og_title":"IGNORANCIA de AUTORIDADES SANITARIAS","og_description":"IGNORANCIA de algunas AUTORIDADES SANITARIAS La ozonoterapia para curar el Covid-19 y no le importa lo que diga la administraci\u00f3n","og_url":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/","og_site_name":"- Blog Ozono21","article_published_time":"2021-05-02T11:21:57+00:00","article_modified_time":"2026-02-22T17:57:50+00:00","og_image":[{"width":600,"height":360,"url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png","type":"image\/png"}],"author":"INVESTIGACION Ozono21","twitter_misc":{"Escrito por":"INVESTIGACION Ozono21","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/#article","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/"},"author":{"name":"INVESTIGACION Ozono21","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/09b7d3e74b7c4469cd705f2b20bca17c"},"headline":"IGNORANCIA de algunas AUTORIDADES SANITARIAS","datePublished":"2021-05-02T11:21:57+00:00","dateModified":"2026-02-22T17:57:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/"},"wordCount":472,"commentCount":0,"image":{"@id":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png","keywords":["Salud","Sociedad","Toxinas","Virus"],"articleSection":["Salud","Sociedad","Toxinas","Virus"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/","url":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/","name":"IGNORANCIA de AUTORIDADES SANITARIAS","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/#primaryimage"},"image":{"@id":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png","datePublished":"2021-05-02T11:21:57+00:00","dateModified":"2026-02-22T17:57:50+00:00","author":{"@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/09b7d3e74b7c4469cd705f2b20bca17c"},"description":"IGNORANCIA de algunas AUTORIDADES SANITARIAS La ozonoterapia para curar el Covid-19 y no le importa lo que diga la administraci\u00f3n","breadcrumb":{"@id":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/#primaryimage","url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png","contentUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png","width":600,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.ozono21.com\/blog\/sociedad\/ignorancia-de-algunas-autoridades-sanitarias\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ozono21.com\/blog\/"},{"@type":"ListItem","position":2,"name":"IGNORANCIA de algunas AUTORIDADES SANITARIAS"}]},{"@type":"WebSite","@id":"https:\/\/www.ozono21.com\/blog\/#website","url":"https:\/\/www.ozono21.com\/blog\/","name":"Blog Ozono21","description":" - Blog Ozono21","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ozono21.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/09b7d3e74b7c4469cd705f2b20bca17c","name":"INVESTIGACION Ozono21","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g","caption":"INVESTIGACION Ozono21"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5226976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/users\/46969"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/comments?post=5226976"}],"version-history":[{"count":0,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5226976\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media\/5225417"}],"wp:attachment":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media?parent=5226976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/categories?post=5226976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/tags?post=5226976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}