{"id":5225505,"date":"2020-03-24T00:11:23","date_gmt":"2020-03-23T22:11:23","guid":{"rendered":"https:\/\/www.ozono21.com\/blog\/?p=5225505"},"modified":"2026-02-15T11:00:37","modified_gmt":"2026-02-15T09:00:37","slug":"agua-con-ozono-contra-la-infeccion-del-virus-corona","status":"publish","type":"post","link":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/","title":{"rendered":"AGUA con OZONO contra la INFECCI\u00f3N del VIRUS CORONA"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" style=\"MARGIN: 10px 0px 10px 10px;  border: 0px;\"  src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS-300x180.png\" alt=\"VIRUS CORONA\" width=\"300\" height=\"180\" class=\"alignright size-medium wp-image-5225417\" title=\"Eficaz el OZONO para MATAR COVID-19\" srcset=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS-300x180.png 300w, https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>AGUA con OZONO en actividades diarias para curar y protegernos, contra la infecci\u00f3n del virus corona<\/p>\n<p><a title=\"AGUA PURIFICADA con OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/agua-purificada-ozono-2\/512\/\" target=\"_blank\" rel=\"noopener noreferrer\">El virus Corona o el nuevo coronavirus de 2019 es una tragedia, ya que se est\u00e1 extendiendo a nivel mundial ahora m\u00e1s all\u00e1 de las fronteras chinas<\/a><\/h2>\n<\/p>\n<p style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\"><a title=\"AIRE PURIFICADO con OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/aire-purificado-ozono\/431\/\"  rel=\"noopener noreferrer\">Los coronavirus (CoV) son una gran familia de virus que causan enfermedades que van desde el resfriado com\u00fan hasta enfermedades m\u00e1s graves, como el s\u00edndrome respiratorio de Medio Oriente (MERS-CoV) y el s\u00edndrome respiratorio agudo severo (SARS-CoV). Un nuevo coronavirus (nCoV) es una nueva cepa que no se ha identificado previamente en humanos<\/a><\/h2>\n<\/p>\n<p style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\"><a title=\"DESINFECCION y LIMPIEZA con OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/desinfeccion-limpieza-ozono\/426\/\" target=\"_blank\" rel=\"noopener noreferrer\">Los coronavirus son zoon\u00f3ticos, lo que significa que se transmiten entre animales y personas.  Investigaciones detalladas encontraron que el SARS-CoV se transmiti\u00f3 de gatos de civeta a humanos y el MERS-CoV de camellos de dromedario a humanos. Varios coronavirus conocidos circulan en animales que a\u00fan no han infectado a los humanos<\/a><\/h2>\n<\/p>\n<p style=\"text-align: justify;\">Los <strong><u>signos comunes de infecci\u00f3n incluyen s\u00edntomas respiratorios, fiebre, tos, dificultad para respirar y dificultades para respirar<\/u><\/strong>. En casos m\u00e1s graves, la infecci\u00f3n puede causar neumon\u00eda, s\u00edndrome respiratorio agudo severo, insuficiencia renal e incluso la muerte.<\/p>\n<p style=\"text-align: justify;\">Las <big><strong>recomendaciones est\u00e1ndar para prevenir la propagaci\u00f3n de la infecci\u00f3n<\/strong><\/big> incluyen lavarse las manos regularmente, cubrirse la boca y la nariz al toser y estornudar, cocinar bien la carne y los huevos. Evite el contacto cercano con cualquier persona que presente s\u00edntomas de enfermedades respiratorias, como tos y estornudos.<\/p>\n<p style=\"text-align: justify;\"><big><strong><a title=\"consulte - OMS\" href=\"https:\/\/translate.google.com\/translate?depth=1&#038;hl=es&#038;prev=search&#038;rurl=translate.google.es&#038;sl=en&#038;sp=nmt4&#038;u=https:\/\/www.who.int\/emergencies\/diseases\/novel-coronavirus-2019\/advice-for-public\" target=\"_blank\" rel=\"noopener noreferrer\">Medidas de protecci\u00f3n b\u00e1sicas contra el nuevo coronavirus, consulte &#8211; OMS<\/a><\/strong><\/big><\/p>\n<p style=\"text-align: justify;\"><big><strong><a title=\"consulte - OMS\" href=\"https:\/\/translate.google.com\/translate?depth=1&#038;hl=es&#038;prev=search&#038;rurl=translate.google.es&#038;sl=en&#038;sp=nmt4&#038;u=https:\/\/www.who.int\/emergencies\/diseases\/novel-coronavirus-2019\/technical-guidance\" target=\"_blank\" rel=\"noopener noreferrer\">Puede consultar m\u00e1s documentos t\u00e9cnicos relacionados con el nuevo virus Corona publicado en la OMS<\/a><\/strong><\/big><\/p>\n<p style=\"text-align: justify;\"><big><strong><a title=\"consulte - OMS\" href=\"https:\/\/translate.google.com\/translate?depth=1&#038;hl=es&#038;prev=search&#038;rurl=translate.google.es&#038;sl=en&#038;sp=nmt4&#038;u=https:\/\/www.who.int\/news-room\/q-a-detail\/q-a-coronaviruses\" target=\"_blank\" rel=\"noopener noreferrer\">Preguntas y respuestas sobre el nuevo virus Corona proporcionado por la OMS<\/a><\/strong><\/big><\/p>\n<p style=\"text-align: justify;\">Ahora tocando el tema principal sobre la posibilidad de utilizar micro nano burbujas de OZONO, la terapia de OZONO y las actividades diarias de rutina para curar y proteger contra la infecci\u00f3n por el virus corona.<\/p>\n<p style=\"text-align: justify;\"><big><strong>Una cosa para recordar y comprender antes de leer e interpretar este art\u00edculo<\/strong><\/big><\/p>\n<p style=\"text-align: justify;\"><strong>1.<\/strong>\t El OZONO es un <big><strong><a title=\"ACCIONES DEL OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/acciones-del-ozono\/102\/\" target=\"_blank\" rel=\"noopener noreferrer\">agente oxidante muy fuerte<\/a><\/strong><\/big>.<\/p>\n<p style=\"text-align: justify;\"><strong>2.<\/strong>\t El OZONO en forma de gas si se inhala en exceso es perjudicial para los humanos.<\/p>\n<p style=\"text-align: justify;\"><strong>3.<\/strong>\t <big><strong><a title=\"ACCIONES DEL OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/accion-del-ozono\/423\/\" target=\"_blank\" rel=\"noopener noreferrer\">El OZONO ya se est\u00e1 utilizando para esterilizar y desinfectar agua, mariscos, verduras, frutas, aguas residuales, aguas residuales, efluentes y otros art\u00edculos.<\/a><\/strong><\/big><\/p>\n<p style=\"text-align: justify;\"><strong>4.<\/strong>\t Hoy el <big><strong><a title=\"COMBATIR ENFERMEDADES con OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/combatir-enfermedades-ozono\/429\/\" target=\"_blank\" rel=\"noopener noreferrer\">OZONO ya se est\u00e1 utilizando para diversas aplicaciones m\u00e9dicas<\/a><\/strong><\/big>, como desinfectar equipos m\u00e9dicos, para tratar <big><strong><a title=\"Tratamientos con OZONO. Desinfecci\u00f3n de heridas y u\u00f1eros en pocos minutos\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/tratamientos-ozono-desinfeccion-heridas-uneros-pocos-minutos\/220\/\" target=\"_blank\" rel=\"noopener noreferrer\">heridas infectadas<\/a><\/strong><\/big>, trastornos circulatorios, trastornos geri\u00e1tricos, degeneraci\u00f3n macular, enfermedades virales, <big><strong><a title=\"OZONOTERAPIA Soluci\u00f3n a los Dolores Reum\u00e1ticos\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/ozonoterapia-solucion-dolores-reumaticos\/217\/\" target=\"_blank\" rel=\"noopener noreferrer\">reumatismo<\/a><\/strong><\/big> y <big><strong><a title=\"Alivie su DOLOR utilizando OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/alivie-su-dolor-utilizando-ozono\/494\/\" target=\"_blank\" rel=\"noopener noreferrer\">artritis<\/a><\/strong><\/big>, <big><strong><a title=\"AGUA OZONIZADA contra el CANCER\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/agua-ozonizada-contra-cancer\/376\/\" target=\"_blank\" rel=\"noopener noreferrer\">c\u00e1ncer<\/a><\/strong><\/big>, SARS, SIDA.  (Referencia: https:\/\/www.medicalnewstoday.com\/articles\/320759.php#uses )<\/p>\n<p style=\"text-align: justify;\"><strong>5.<\/strong>\t Aunque el OZONO es un gas, los desarrollos tecnol\u00f3gicos significan que puede usarse de varias formas y de diferentes maneras, incluyendo: <big><strong><a title=\"ACEITE DE OLIVA OZONIZADO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/aceite-de-oliva-ozonizado\/205\/\" target=\"_blank\" rel=\"noopener noreferrer\">aceite de oliva ozonizado<\/a><\/strong><\/big> aplicado directamente al cuerpo, insuflaci\u00f3n, una terapia arriesgada en la que se inyecta OZONO en el recto, autohemoterapia, donde la sangre est\u00e1 retirada, mezclado con OZONO y puesto nuevamente en el torrente sangu\u00edneo.  (Referencia: https:\/\/www.medicalnewstoday.com\/articles\/320759.php#uses )<\/p>\n<p style=\"text-align: justify;\"><strong>6.<\/strong>\t Lea este art\u00edculo detallado sobre el OZONO en para comprender en detalle: https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC3312702\/ <\/p>\n<p style=\"text-align: justify;\"><strong>7.<\/strong>\t Nunca realice la aplicaci\u00f3n m\u00e9dica de OZONO sin supervisi\u00f3n profesional.<\/p>\n<p style=\"text-align: justify;\"><strong>8.<\/strong>\t El <strong>l\u00edmite de exposici\u00f3n recomendado<\/strong> por el NIOSH para el OZONO es de 0.1 ppm (0.2 mg \/ m 3 ).  Seg\u00fan NIOSH, los niveles de OZONO de 5 ppm o m\u00e1s se consideran inmediatamente peligrosos para la vida o la salud.<\/p>\n<p style=\"text-align: justify;\"><strong>9.<\/strong>\t <big><strong>Lo m\u00e1s importante es que el OZONO controlado es excelente<\/strong><\/big>, el OZONO no controlado es peor cuando se considera la aplicaci\u00f3n m\u00e9dica.<\/p>\n<p style=\"text-align: justify;\"><big><strong><a title=\"INDUSTRIA de ALIMENTOS con OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/industria-alimentos-ozono-1\/515\/\" target=\"_blank\" rel=\"noopener noreferrer\">Para otras aplicaciones no m\u00e9dicas como la esterilizaci\u00f3n, la desinfecci\u00f3n de alimentos, carnes, mariscos, verduras y frutas, m\u00e1s OZONO, son los mejores resultados.<\/a><\/strong><\/big><\/p>\n<p style=\"text-align: justify;\">En base a todo lo mencionado, podemos entender que <strong>en este momento el OZONO parece ser una soluci\u00f3n prometedora contra el virus corona<\/strong>, pero es necesario realizar muchas investigaciones y ensayos.<\/p>\n<p style=\"text-align: justify;\">Especialmente <strong>los cient\u00edficos deben probar el comportamiento del virus corona contra el OZONO a diferentes dosis de concentraci\u00f3n<\/strong>.  Los ensayos deben tomarse tomando muestras de sangre de una persona infectada y tratar esa sangre haciendo micro nano burbujas de OZONO en esa sangre y estudiar el efecto sobre la infecci\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><a title=\"Generadores de Ozono 21\" href=\"https:\/\/www.ozono21.com\/productos-ozono\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" style=\"MARGIN: 20px 10px 20px 0px;  border: 0px;\"   title=\"MARAVILLOSA AGUA con OZONO\"  src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/01\/vitale21_ozone_boy-300x210.jpg\" alt=\"VIRUS CORONA\" width=\"300\" height=\"210\" class=\"alignleft size-medium wp-image-5225292\" srcset=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/01\/vitale21_ozone_boy-300x210.jpg 300w, https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/01\/vitale21_ozone_boy-250x175.jpg 250w, https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/01\/vitale21_ozone_boy.jpg 314w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><big><strong><u>Primero<\/u>,<\/strong><\/big> discutiremos la Protecci\u00f3n y Prevenci\u00f3n contra el virus corona y c\u00f3mo las <big><strong><a title=\"Generadores de Ozono 21\" href=\"https:\/\/www.ozono21.com\/productos-ozono\" target=\"_blank\" rel=\"noopener noreferrer\">Ozone Micro Nano Bubbles y el gas de OZONO pueden ayudarnos en ello.<\/a><\/strong><\/big><\/p>\n<p style=\"text-align: justify;\">Como sabemos por todas las referencias anteriores de la OMS, se entiende que el inicio de la propagaci\u00f3n del virus corona parece ser de animales y mariscos.<\/p>\n<p style=\"text-align: justify;\">Entonces, <big><strong><u>primer paso muy importante<\/u>:<\/strong><\/big> nunca coma carne cruda \/ mariscos o carne \/ mariscos a medio cocinar.  Posiblemente evite comer carne o mariscos hasta que se controle este brote del virus corona y tenga alg\u00fan ant\u00eddoto para este virus.<\/p>\n<p style=\"text-align: justify;\"><big><strong><u>Segundo<\/u>,<\/strong><\/big> mantenga un peque\u00f1o generador de micro nano burbujas de tama\u00f1o dom\u00e9stico con un generador de OZONO para uso dom\u00e9stico en el hogar.<\/p>\n<p style=\"text-align: justify;\"><big><strong><a title=\"Generadores de Ozono 21\" href=\"https:\/\/www.ozono21.com\/productos-ozono\" target=\"_blank\" rel=\"noopener noreferrer\">Y cuando quiera cocinar algo, ya sea carne, mariscos, vegetales o frutas, siempre procese en micro nano burbujas de agua ozonizada para beber.<\/a><\/strong><\/big><\/p>\n<p style=\"text-align: justify;\">Simplemente enju\u00e1guelos en agua burbujeante micro nano, esto <strong>no solo eliminar\u00e1 virus y bacterias, sino que tambi\u00e9n eliminar\u00e1 cualquier pesticida, qu\u00edmico o antibi\u00f3tico<\/strong> que contenga.<\/p>\n<p style=\"text-align: justify;\">Limpie sus almohadillas de corte, cuchillos y guantes de mano con agua ozonizada.<\/p>\n<p style=\"text-align: justify;\"><big><strong><u>Tercero<\/u>,<\/strong><\/big> use <big><strong><a title=\"Generadores de Ozono 21\" href=\"https:\/\/www.ozono21.com\/productos-ozono\" target=\"_blank\" rel=\"noopener noreferrer\">purificadores de aire con OZONO para desinfectar la atm\u00f3sfera en habitaciones, oficinas, hospitales, etc.<\/a><\/strong><\/big><\/p>\n<p style=\"text-align: justify;\">Hay difusores de OZONO port\u00e1tiles disponibles en el mercado para desinfectar el aire en \u00e1reas, el proceso consiste en un paso muy simple como cerrar esa \u00e1rea en particular y comenzar ese OZONO a la desinfecci\u00f3n del aire por un tiempo recomendado por los profesionales de generadores de OZONO.<\/p>\n<p style=\"text-align: justify;\">Esto no solo eliminar\u00e1 el mal olor, sino que tambi\u00e9n matar\u00e1 los virus y bacterias nacidos en el aire. Recuerde <strong>no estar presente en esa \u00e1rea cerrada cuando se est\u00e1 produciendo el OZONO<\/strong>. Una vez que se apaga el equipo de OZONO, abra todas las ventanas y puertas y espere hasta 30 minutos y luego ingrese a esa \u00e1rea.<\/p>\n<p style=\"text-align: justify;\"><big><strong><u>Cuarto<\/u><\/strong><\/big>, intente practicar una <strong>metodolog\u00eda antigua para limpiar su casa, oficina o habitaciones<\/strong>. Por ejemplo, en la antigua cultura india se dice que hace \u00abDHOOP (liberar humo de algunos ingredientes herbales mientras se hacen oraciones diarias por la ma\u00f1ana)\u00bb todas las ma\u00f1anas.  Este proceso consiste en quemar una mezcla de ingredientes herbales y ayurv\u00e9dicos como NEEM (Azadirachta indica), GUGAL (\u00e1rbol de bedelio indio &#8211; Commiphora wightii), KApur (CAMPHOR), aceite de eucalipto y otros.  Libere el humo descargado de esta mezcla que se quema a su alrededor, como en su casa, etc. Esto limpiar\u00e1 el aire de bacterias y virus.<\/p>\n<p style=\"text-align: justify;\"><big><strong><u>Quinto,<\/u><\/strong><\/big> practique <strong>alimentos saludables y veganos, ya que teniendo en cuenta este caso de infecci\u00f3n por el virus corona, se ve claramente que se origina en alimentos no vegetales<\/strong>. Por lo tanto, intente practicar la m\u00e1xima cantidad de alimentos veganos, tome alimentos no vegetales muy raramente si es necesario para necesitar prote\u00ednas y vitaminas B12.  Elija bebidas saludables para sus bebidas.  La mayor\u00eda del mundo bebe t\u00e9 y caf\u00e9, trata de obtener un buen t\u00e9 verde org\u00e1nico en tus h\u00e1bitos diarios, esto estimular\u00e1 tu sistema inmunol\u00f3gico.  Hay un mont\u00f3n de buen t\u00e9 verde org\u00e1nico potenciado con ingredientes a base de hierbas como el t\u00e9.<\/p>\n<p style=\"text-align: justify;\"><big><strong><u>Sexto<\/u>,<\/strong><\/big> siga las <strong>pautas de la OMS<\/strong> para practicar la higiene de rutina como se mencion\u00f3 anteriormente en la introducci\u00f3n de este art\u00edculo.<\/p>\n<p style=\"text-align: justify;\"><big><strong>Ahora vamos a discutir las posibilidades de curar la infecci\u00f3n del virus corona<\/strong><\/big><\/p>\n<p style=\"text-align: justify;\">Oramos para que la infecci\u00f3n por el virus de la corona ya no se propague, pero qu\u00e9 pasa si te infectas con el virus de la corona.<\/p>\n<p style=\"text-align: justify;\"><strong>Lo primero es lo primero, consulte a los servicios m\u00e9dicos m\u00e1s cercanos e intente diagnosticar, si es una infecci\u00f3n real por el virus de la corona o no<\/strong>. Como en este caos del virus corona, muchos piensan que se infectan con \u00e9l incluso cuando tienen un resfriado o gripe normal.<\/p>\n<p style=\"text-align: justify;\">Entonces, lo primero es diagnosticar, es posible que tenga s\u00edntomas de que no es necesario que su infecci\u00f3n por el virus de la corona ya que los s\u00edntomas de la infecci\u00f3n por el virus de la corona son similares al resfriado, la tos y la gripe normales. As\u00ed que no se asuste y sea diagnosticado.<\/p>\n<p style=\"text-align: justify;\"><strong>Si se encontr\u00f3 infectado con el virus corona, lo principal que debe hacer es<\/strong> aislarse y tomar protecciones como tener m\u00e1scaras faciales para que no infecte a su ser querido una vez. Mantenga una distancia de al menos 1 metro con todos los dem\u00e1s. De esta manera, ayudar\u00e1 a evitar que la infecci\u00f3n se propague a\u00fan m\u00e1s.<\/p>\n<p style=\"text-align: justify;\">Ahora, <strong>bajo supervisi\u00f3n profesional, intente tomar varias terapias de OZONO.  Comience a tomar inhalaci\u00f3n de OZONO no m\u00e1s de 0.05 ppm de dosis en la inhalaci\u00f3n durante un m\u00e1ximo de 10 minutos.<\/strong><\/p>\n<p style=\"text-align: justify;\">Practica esto diariamente una vez. <strong>Como est\u00e1 tomando OZONO directamente en su sistema respiratorio, debe ser muy cauteloso<\/strong>, ya que si la dosis de OZONO aumenta a m\u00e1s de 0.1 ppm, da\u00f1ar\u00e1 sus tejidos pulmonares.  Pero a 0.05 ppm matar\u00e1 virus y bacterias en su sistema respiratorio.<\/p>\n<p style=\"text-align: justify;\">Esto tambi\u00e9n aumentar\u00e1 la generaci\u00f3n de radicales libres, as\u00ed que intente tomar buenos antioxidantes como el resveratrol diariamente en forma natural. Un adulto normal necesitar\u00e1 150 mg de resveratrol diariamente para un buen efecto antioxidante. Evite administrar resveratrol a mujeres embarazadas y ni\u00f1os. Tampoco le d\u00e9 resveratrol a una persona con enfermedad autoinmune.<\/p>\n<p style=\"text-align: justify;\"><strong>M\u00e1s all\u00e1 de esta terapia de OZONO respiratorio, si es necesario, intente obtener autohemoterapia con OZONO, donde se extrae sangre, se mezcla con OZONO y se vuelve a colocar en el torrente sangu\u00edneo bajo supervisi\u00f3n profesional solo para eliminar la infecci\u00f3n por el virus corona de su sangre.<\/strong><\/p>\n<p style=\"text-align: justify;\">Esto tomar\u00e1 poco tiempo ya que necesita introducir micro y nano burbujas de OZONO en el torrente sangu\u00edneo, funcionar\u00e1 como un sistema de administraci\u00f3n de medicamentos dirigido. Pero este paso debe considerarse como el \u00faltimo recurso disponible para curarse de la infecci\u00f3n por el virus corona. Como todav\u00eda hay muchas investigaciones en curso para esta terapia y hay pocos efectos secundarios tambi\u00e9n mencionados por los investigadores.<\/p>\n<p style=\"text-align: justify;\">Lea este art\u00edculo para obtener m\u00e1s detalles https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC3312702\/ <\/p>\n<p style=\"text-align: justify;\"><strong>Toda esta informaci\u00f3n se acumula de varios art\u00edculos disponibles en Internet y se edita para que sea f\u00e1cil de entender.  Algunas referencias se enumeran a continuaci\u00f3n.<\/strong><\/p>\n<ul>\n<li>https:\/\/www.medicalnewstoday.com\/articles\/320759.php<\/li>\n<li>https:\/\/www.ncbi.nlm.nih.gov\/pmc\/articles\/PMC3312702\/<\/li>\n<li>https:\/\/www.healthline.com\/health\/ozone-therapy<\/li>\n<li>https:\/\/en.wikipedia.org\/wiki\/Ozone_therapy<\/li>\n<li>https:\/\/www.thelifeco.com\/en\/ozone-therapy\/<\/li>\n<li>https:\/\/www.lifeworkswellnesscenter.com\/ozone-therapy\/side-effects-of-ozone-therapy.html<\/li>\n<li>https:\/\/www.hindawi.com\/journals\/ecam\/2018\/7931849\/<\/li>\n<li>http:\/\/www.triroc.com\/sunnen\/topics\/sars.html<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Solo esperamos que esta informaci\u00f3n ayude a la sociedad a superar esta tragedia de infecci\u00f3n por el virus corona<\/strong><\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Actualidad ACCION del OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/accion-del-ozono\/423\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Noticias-Relacionadas.png\" alt=\"Noticias Relacionadas\" width=\"600\" height=\"25\" border=\"0\"><\/a><\/strong>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<ul><big><strong><\/p>\n<li><a title=\"Eficaz el OZONO para MATAR el coronavirus COVID-19\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/blog\/virus\/eficaz-el-ozono-para-matar-coronavirus_covid-19\/\"  rel=\"noopener noreferrer\">Eficaz el OZONO para MATAR el coronavirus COVID-19<\/a><\/li>\n<li><a title=\"CORONAVIRUS muerto GRACIAS a el OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/coronavirus-muerto-gracias-ozono\/555\/\"  rel=\"noopener noreferrer\">CORONAVIRUS muerto GRACIAS a el OZONO<\/a><\/li>\n<li><a title=\"OZONO para desinfectar y luchar contra el CORONAVIRUS\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/ozono-para-desinfectar-luchar-contra-coronavirus\/554\/\"  rel=\"noopener noreferrer\">OZONO para desinfectar y luchar contra el CORONAVIRUS<\/a><\/li>\n<p><\/strong><\/big>\n<\/ul>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td width=\"600\" height=\"25\" align=\"center\" bgcolor=\"#3b7cff\"><strong><a title=\"Videos YouTube\" target=\"_blank\" href=\"http:\/\/www.youtube.com\/user\/ozono21\/videos?sort=p&amp;view=0&amp;flow=grid\"  rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"25\" alt=\"Videos Youtube\" border=\"0\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Videos-Youtube.png\" \/><\/a><\/strong> <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" width=\"853\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/YVP-0nN1hwM\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/R5_qeyni9iI\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" width=\"720\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/NIyZLA2n1vw\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5225505\" class=\"pvc_stats total_only  \" data-element-id=\"5225505\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>AGUA con OZONO en actividades diarias para curar y protegernos, contra la infecci\u00f3n del virus corona El virus Corona o el nuevo coronavirus de 2019 es una tragedia, ya que se est\u00e1 extendiendo a nivel mundial ahora m\u00e1s all\u00e1 de &hellip; <a href=\"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5225505\" class=\"pvc_stats total_only  \" data-element-id=\"5225505\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":46969,"featured_media":5225417,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[6,67,38,14,10,7,48,15],"tags":[68,65,37,77,72,21,81,29],"class_list":["post-5225505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agua","category-desinfeccion","category-ecologico-2","category-ozono","category-ozono21","category-salud","category-sociedad","category-virus","tag-agua","tag-desinfeccion","tag-ecologico","tag-ozono","tag-ozono21","tag-salud-2","tag-sociedad","tag-virus-2"],"a3_pvc":{"activated":true,"total_views":4112,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AGUA con OZONO INFECCI\u00f3N VIRUS CORONA<\/title>\n<meta name=\"description\" content=\"AGUA con OZONO contra la INFECCI\u00f3N del VIRUS CORONA. AGUA con OZONO en actividades diarias para curar y protegernos, infecci\u00f3n virus corona\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AGUA con OZONO INFECCI\u00f3N VIRUS CORONA\" \/>\n<meta property=\"og:description\" content=\"AGUA con OZONO contra la INFECCI\u00f3N del VIRUS CORONA. AGUA con OZONO en actividades diarias para curar y protegernos, infecci\u00f3n virus corona\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/\" \/>\n<meta property=\"og:site_name\" content=\"- Blog Ozono21\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-23T22:11:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-15T09:00:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"INVESTIGACION Ozono21\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"INVESTIGACION Ozono21\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/virus\\\/agua-con-ozono-contra-la-infeccion-del-virus-corona\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/virus\\\/agua-con-ozono-contra-la-infeccion-del-virus-corona\\\/\"},\"author\":{\"name\":\"INVESTIGACION Ozono21\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/09b7d3e74b7c4469cd705f2b20bca17c\"},\"headline\":\"AGUA con OZONO contra la INFECCI\u00f3N del VIRUS CORONA\",\"datePublished\":\"2020-03-23T22:11:23+00:00\",\"dateModified\":\"2026-02-15T09:00:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/virus\\\/agua-con-ozono-contra-la-infeccion-del-virus-corona\\\/\"},\"wordCount\":1907,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/virus\\\/agua-con-ozono-contra-la-infeccion-del-virus-corona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CORONAVIRUS.png\",\"keywords\":[\"Agua\",\"DESINFECCION\",\"Ecol\u00f3gico\",\"OZONO\",\"Ozono21\",\"Salud\",\"Sociedad\",\"Virus\"],\"articleSection\":[\"Agua\",\"DESINFECCION\",\"Ecol\u00f3gico\",\"OZONO\",\"Ozono21\",\"Salud\",\"Sociedad\",\"Virus\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/virus\\\/agua-con-ozono-contra-la-infeccion-del-virus-corona\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/virus\\\/agua-con-ozono-contra-la-infeccion-del-virus-corona\\\/\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/virus\\\/agua-con-ozono-contra-la-infeccion-del-virus-corona\\\/\",\"name\":\"AGUA con OZONO INFECCI\u00f3N VIRUS CORONA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/virus\\\/agua-con-ozono-contra-la-infeccion-del-virus-corona\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/virus\\\/agua-con-ozono-contra-la-infeccion-del-virus-corona\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CORONAVIRUS.png\",\"datePublished\":\"2020-03-23T22:11:23+00:00\",\"dateModified\":\"2026-02-15T09:00:37+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/09b7d3e74b7c4469cd705f2b20bca17c\"},\"description\":\"AGUA con OZONO contra la INFECCI\u00f3N del VIRUS CORONA. AGUA con OZONO en actividades diarias para curar y protegernos, infecci\u00f3n virus corona\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/virus\\\/agua-con-ozono-contra-la-infeccion-del-virus-corona\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/virus\\\/agua-con-ozono-contra-la-infeccion-del-virus-corona\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/virus\\\/agua-con-ozono-contra-la-infeccion-del-virus-corona\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CORONAVIRUS.png\",\"contentUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/CORONAVIRUS.png\",\"width\":600,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/virus\\\/agua-con-ozono-contra-la-infeccion-del-virus-corona\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AGUA con OZONO contra la INFECCI\u00f3N del VIRUS CORONA\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\",\"name\":\"Blog Ozono21\",\"description\":\" - Blog Ozono21\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/09b7d3e74b7c4469cd705f2b20bca17c\",\"name\":\"INVESTIGACION Ozono21\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g\",\"caption\":\"INVESTIGACION Ozono21\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AGUA con OZONO INFECCI\u00f3N VIRUS CORONA","description":"AGUA con OZONO contra la INFECCI\u00f3N del VIRUS CORONA. AGUA con OZONO en actividades diarias para curar y protegernos, infecci\u00f3n virus corona","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/","og_locale":"es_ES","og_type":"article","og_title":"AGUA con OZONO INFECCI\u00f3N VIRUS CORONA","og_description":"AGUA con OZONO contra la INFECCI\u00f3N del VIRUS CORONA. AGUA con OZONO en actividades diarias para curar y protegernos, infecci\u00f3n virus corona","og_url":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/","og_site_name":"- Blog Ozono21","article_published_time":"2020-03-23T22:11:23+00:00","article_modified_time":"2026-02-15T09:00:37+00:00","og_image":[{"width":600,"height":360,"url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png","type":"image\/png"}],"author":"INVESTIGACION Ozono21","twitter_misc":{"Escrito por":"INVESTIGACION Ozono21","Tiempo de lectura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/#article","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/"},"author":{"name":"INVESTIGACION Ozono21","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/09b7d3e74b7c4469cd705f2b20bca17c"},"headline":"AGUA con OZONO contra la INFECCI\u00f3N del VIRUS CORONA","datePublished":"2020-03-23T22:11:23+00:00","dateModified":"2026-02-15T09:00:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/"},"wordCount":1907,"commentCount":0,"image":{"@id":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png","keywords":["Agua","DESINFECCION","Ecol\u00f3gico","OZONO","Ozono21","Salud","Sociedad","Virus"],"articleSection":["Agua","DESINFECCION","Ecol\u00f3gico","OZONO","Ozono21","Salud","Sociedad","Virus"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/","url":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/","name":"AGUA con OZONO INFECCI\u00f3N VIRUS CORONA","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/#primaryimage"},"image":{"@id":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png","datePublished":"2020-03-23T22:11:23+00:00","dateModified":"2026-02-15T09:00:37+00:00","author":{"@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/09b7d3e74b7c4469cd705f2b20bca17c"},"description":"AGUA con OZONO contra la INFECCI\u00f3N del VIRUS CORONA. AGUA con OZONO en actividades diarias para curar y protegernos, infecci\u00f3n virus corona","breadcrumb":{"@id":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/#primaryimage","url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png","contentUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png","width":600,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/www.ozono21.com\/blog\/virus\/agua-con-ozono-contra-la-infeccion-del-virus-corona\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ozono21.com\/blog\/"},{"@type":"ListItem","position":2,"name":"AGUA con OZONO contra la INFECCI\u00f3N del VIRUS CORONA"}]},{"@type":"WebSite","@id":"https:\/\/www.ozono21.com\/blog\/#website","url":"https:\/\/www.ozono21.com\/blog\/","name":"Blog Ozono21","description":" - Blog Ozono21","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ozono21.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/09b7d3e74b7c4469cd705f2b20bca17c","name":"INVESTIGACION Ozono21","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g","caption":"INVESTIGACION Ozono21"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2020\/03\/CORONAVIRUS.png","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5225505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/users\/46969"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/comments?post=5225505"}],"version-history":[{"count":0,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5225505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media\/5225417"}],"wp:attachment":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media?parent=5225505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/categories?post=5225505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/tags?post=5225505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}