{"id":5221233,"date":"2018-09-14T13:41:40","date_gmt":"2018-09-14T11:41:40","guid":{"rendered":"https:\/\/www.ozono21.com\/blog\/?p=5221233"},"modified":"2026-03-24T16:30:53","modified_gmt":"2026-03-24T14:30:53","slug":"contaminacion-en-el-hogar","status":"publish","type":"post","link":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/","title":{"rendered":"CONTAMINACION en el HOGAR"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420-300x225.gif\" alt=\"CONTAMINACION\" width=\"300\" height=\"225\" class=\"alignleft size-medium wp-image-5205410\" title=\"CONTAMINACION en el HOGAR\"  style=\"margin: 20px 10px 10px 0px; cursor: hand; border: 0px;\"  \/>Reducir la CONTAMINACION en los hogares es vital<\/p>\n<p><a title=\"En nuestro Hogar el generador de OZONO consigue nuestro \u201cPARA\u00cdSO\u201d\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/en-nuestro-hogar-generador-ozono-consigue-nuestro-paraiso\/348\/\" target=\"_blank\" rel=\"noopener noreferrer\">El experto en calidad del aire Carles Suri\u00e0 ha criticado que existe una \u00abfalta de legislaci\u00f3n y de informaci\u00f3n\u00bb sobre CONTAMINACION en zonas interiores, y ha apostado por reducirla para disminuir el gasto sanitario y los periodos de baja.<\/a><\/h2>\n<\/p>\n<p style=\"text-align: justify;\">\u00abSi nos pasamos la mayor parte del tiempo en espacios cerrados, <strong>\u00bfpor qu\u00e9 no nos preocupamos m\u00e1s por el aire que respiramos en casa o en la oficina?.<\/strong> Muchos de los contaminantes legislados para el aire exterior tienen valores muy superiores en los espacios interiores\u00bb, asegura Suri\u00e0, ingeniero experto en mediciones de calidad del aire.<\/p>\n<p style=\"text-align: justify;\">Para este especialista, <strong>la sociedad \u00abtodav\u00eda no es consciente\u00bb del nivel de CONTAMINACION que hay dentro de sus hogares, \u00absuperior al de la calle\u00bb.<\/strong> \u00abYa en un estudio realizado hace 30 a\u00f1os se demostraba que agentes contaminantes exteriores como el plomo, el cadmio, el ars\u00e9nico, el benzopireno o el benceno presentaban valores de entre 2 a 5 veces superiores en zonas cerradas\u00bb, explica.<\/p>\n<p style=\"text-align: justify;\">Por eso, considera que existe una \u00abgran falta legislativa\u00bb sobre la CONTAMINACION del aire interior, especialmente en las viviendas, y ello se debe a que <strong>los residentes \u00abson los responsables de la CONTAMINACION del aire interior que ellos mismos generan\u00bb<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Ante esta situaci\u00f3n, el experto se cuestiona por qu\u00e9 las administraciones no facilitan m\u00e1s informaci\u00f3n sobre los riesgos o sobre c\u00f3mo actuar. \u00ab\u00bfPor qu\u00e9 las administraciones no ampl\u00edan los est\u00e1ndares de calidad de los productos de consumo para asegurar que no emitan contaminantes al espacio interior? <strong>Es evidente que reducir la CONTAMINACION interior disminuir\u00eda el gasto sanitario y los periodos de baja<\/strong>\u00ab, afirma Suri\u00e0.<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan explica, <strong>estas concentraciones de t\u00f3xicos se deben a una ventilaci\u00f3n insuficiente y tambi\u00e9n a un ambiente artificial provocado por los pl\u00e1sticos y los materiales sint\u00e9ticos que se tienen en casa<\/strong>, lo que provoca que \u00abse genere un ambiente cargado electrost\u00e1ticamente que incrementa la concentraci\u00f3n de polvo en el ambiente interior\u00bb. As\u00ed, las sustancias nocivas que se generan se adhieren a este polvo y permanecen en el aire, detalla.<\/p>\n<p style=\"text-align: justify;\">Entre los contaminantes m\u00e1s frecuentes con valores m\u00e1s altos en los hogares, Suri\u00e0 se\u00f1ala que se encuentran sustancias org\u00e1nicas, como disolventes o hidrocarburos arom\u00e1ticos; gas rad\u00f3n, principalmente en zonas con suelos gran\u00edticos como Galicia; los hongos y \u00e1caros, que causan efectos en las v\u00edas respiratorias; y <strong><a title=\"Efectos nocivos de los compuestos ORGANICOS VOLATILES\" href=\"https:\/\/www.ozono21.com\/blog\/toxinas\/compuestos-organicos-volatiles\/\" target=\"_blank\" rel=\"noopener noreferrer\">las part\u00edculas en suspensi\u00f3n, \u00ablos peores contaminantes para la salud humana y los m\u00e1s frecuentes cuanta m\u00e1s carga electrost\u00e1tica haya en el ambiente\u00bb.<\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><big><strong><a title=\"Generadores de OZONO21\" href=\"https:\/\/www.ozono21.com\/productos-ozono\" target=\"_blank\" rel=\"noopener noreferrer\">Como soluciones, Carles Suri\u00e0 comenta que hay un \u00abgran \u00e1mbito de actuaci\u00f3n\u00bb, como unos h\u00e1bitos de ventilaci\u00f3n correctos, la reducci\u00f3n de fuentes de CONTAMINACION interior como mobiliario y materiales de construcci\u00f3n artificiales, humo de tabaco, productos de limpieza no biodegradables o moquetas, control de la humedad relativa, plantas para purificar ambientes con poca humedad, instalaci\u00f3n de extractores en ba\u00f1os y cocinas, as\u00ed como controles peri\u00f3dicos de la calidad del aire interior, la promoci\u00f3n de cocinas el\u00e9ctricas y campa\u00f1as de informaci\u00f3n.<\/a><\/strong><\/big><\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Actualidad ACCION del OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/accion-del-ozono\/423\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Noticias-Relacionadas.png\" alt=\"Noticias Relacionadas\" width=\"600\" height=\"25\" border=\"0\" \/><\/a><\/strong>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><big><strong><\/p>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td width=\"150\" height=\"150\" ><a title=\" POST sobre el HOGAR \" href=\"https:\/\/www.ozono21.com\/blog\/?s=HOGAR\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420-300x225.gif\" alt=\" CONTAMINACION \"  width=\"140\" height=\"140\" style=\"margin: 10px 10px 0px 50px; cursor: hand; border: 0px;\" \/><\/a><\/td>\n<td width=\"300\" height=\"150\" style=\"text-align: left; vertical-align: middle;\"><strong><a title=\" POST sobre el HOGAR \" href=\"https:\/\/www.ozono21.com\/blog\/?s=HOGAR\" target=\"_blank\" rel=\"noopener noreferrer\">POST sobre el HOGAR<\/a><\/strong><\/li>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/strong><\/big><\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Videos YouTube\" target=\"_blank\" href=\"http:\/\/www.youtube.com\/user\/ozono21\/videos?sort=p&amp;view=0&amp;flow=grid\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Videos-Youtube.png\" alt=\"Videos Youtube\" width=\"600\" height=\"25\" border=\"0\" \/><\/a><\/strong>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: center\"><iframe loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/tz6f5FJmX5E\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: center\"><iframe loading=\"lazy\" width=\"651\" height=\"488\" src=\"https:\/\/www.youtube.com\/embed\/Lcv2xcWmsMU\" title=\"OZONO Purifica TU ambiente\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5221233\" class=\"pvc_stats total_only  \" data-element-id=\"5221233\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Reducir la CONTAMINACION en los hogares es vital El experto en calidad del aire Carles Suri\u00e0 ha criticado que existe una \u00abfalta de legislaci\u00f3n y de informaci\u00f3n\u00bb sobre CONTAMINACION en zonas interiores, y ha apostado por reducirla para disminuir el &hellip; <a href=\"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5221233\" class=\"pvc_stats total_only  \" data-element-id=\"5221233\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":46969,"featured_media":5205410,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[8,17,13,7,48,4],"tags":[69,18,20,74,66,21,81,36],"class_list":["post-5221233","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aire","category-contaminacion","category-medioambiente","category-salud","category-sociedad","category-toxinas","tag-aire","tag-asepsia","tag-contaminacion-2","tag-medioambiente","tag-olor","tag-salud-2","tag-sociedad","tag-toxinas-2"],"a3_pvc":{"activated":true,"total_views":4161,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CONTAMINACION en el HOGAR<\/title>\n<meta name=\"description\" content=\"Reducir la CONTAMINACION en los hogares es vital Falta de legislaci\u00f3n y de informaci\u00f3n sobre CONTAMINACION en zonas interiores\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CONTAMINACION en el HOGAR\" \/>\n<meta property=\"og:description\" content=\"Reducir la CONTAMINACION en los hogares es vital Falta de legislaci\u00f3n y de informaci\u00f3n sobre CONTAMINACION en zonas interiores\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/\" \/>\n<meta property=\"og:site_name\" content=\"- Blog Ozono21\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-14T11:41:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-24T14:30:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"959\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"INVESTIGACION Ozono21\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"INVESTIGACION Ozono21\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/contaminacion\\\/contaminacion-en-el-hogar\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/contaminacion\\\/contaminacion-en-el-hogar\\\/\"},\"author\":{\"name\":\"INVESTIGACION Ozono21\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/09b7d3e74b7c4469cd705f2b20bca17c\"},\"headline\":\"CONTAMINACION en el HOGAR\",\"datePublished\":\"2018-09-14T11:41:40+00:00\",\"dateModified\":\"2026-03-24T14:30:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/contaminacion\\\/contaminacion-en-el-hogar\\\/\"},\"wordCount\":540,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/contaminacion\\\/contaminacion-en-el-hogar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif\",\"keywords\":[\"Aire\",\"Asepsia\",\"Contaminaci\u00f3n\",\"MedioAmbiente\",\"OLOR\",\"Salud\",\"Sociedad\",\"Toxinas\"],\"articleSection\":[\"Aire\",\"Contaminaci\u00f3n\",\"MedioAmbiente\",\"Salud\",\"Sociedad\",\"Toxinas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/contaminacion\\\/contaminacion-en-el-hogar\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/contaminacion\\\/contaminacion-en-el-hogar\\\/\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/contaminacion\\\/contaminacion-en-el-hogar\\\/\",\"name\":\"CONTAMINACION en el HOGAR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/contaminacion\\\/contaminacion-en-el-hogar\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/contaminacion\\\/contaminacion-en-el-hogar\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif\",\"datePublished\":\"2018-09-14T11:41:40+00:00\",\"dateModified\":\"2026-03-24T14:30:53+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/09b7d3e74b7c4469cd705f2b20bca17c\"},\"description\":\"Reducir la CONTAMINACION en los hogares es vital Falta de legislaci\u00f3n y de informaci\u00f3n sobre CONTAMINACION en zonas interiores\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/contaminacion\\\/contaminacion-en-el-hogar\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/contaminacion\\\/contaminacion-en-el-hogar\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/contaminacion\\\/contaminacion-en-el-hogar\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif\",\"contentUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/04\\\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif\",\"width\":959,\"height\":719},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/contaminacion\\\/contaminacion-en-el-hogar\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CONTAMINACION en el HOGAR\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\",\"name\":\"Blog Ozono21\",\"description\":\" - Blog Ozono21\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/09b7d3e74b7c4469cd705f2b20bca17c\",\"name\":\"INVESTIGACION Ozono21\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g\",\"caption\":\"INVESTIGACION Ozono21\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CONTAMINACION en el HOGAR","description":"Reducir la CONTAMINACION en los hogares es vital Falta de legislaci\u00f3n y de informaci\u00f3n sobre CONTAMINACION en zonas interiores","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/","og_locale":"es_ES","og_type":"article","og_title":"CONTAMINACION en el HOGAR","og_description":"Reducir la CONTAMINACION en los hogares es vital Falta de legislaci\u00f3n y de informaci\u00f3n sobre CONTAMINACION en zonas interiores","og_url":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/","og_site_name":"- Blog Ozono21","article_published_time":"2018-09-14T11:41:40+00:00","article_modified_time":"2026-03-24T14:30:53+00:00","og_image":[{"width":959,"height":719,"url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif","type":"image\/gif"}],"author":"INVESTIGACION Ozono21","twitter_misc":{"Escrito por":"INVESTIGACION Ozono21","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/#article","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/"},"author":{"name":"INVESTIGACION Ozono21","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/09b7d3e74b7c4469cd705f2b20bca17c"},"headline":"CONTAMINACION en el HOGAR","datePublished":"2018-09-14T11:41:40+00:00","dateModified":"2026-03-24T14:30:53+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/"},"wordCount":540,"commentCount":0,"image":{"@id":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif","keywords":["Aire","Asepsia","Contaminaci\u00f3n","MedioAmbiente","OLOR","Salud","Sociedad","Toxinas"],"articleSection":["Aire","Contaminaci\u00f3n","MedioAmbiente","Salud","Sociedad","Toxinas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/","url":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/","name":"CONTAMINACION en el HOGAR","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/#primaryimage"},"image":{"@id":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif","datePublished":"2018-09-14T11:41:40+00:00","dateModified":"2026-03-24T14:30:53+00:00","author":{"@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/09b7d3e74b7c4469cd705f2b20bca17c"},"description":"Reducir la CONTAMINACION en los hogares es vital Falta de legislaci\u00f3n y de informaci\u00f3n sobre CONTAMINACION en zonas interiores","breadcrumb":{"@id":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/#primaryimage","url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif","contentUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif","width":959,"height":719},{"@type":"BreadcrumbList","@id":"https:\/\/www.ozono21.com\/blog\/contaminacion\/contaminacion-en-el-hogar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ozono21.com\/blog\/"},{"@type":"ListItem","position":2,"name":"CONTAMINACION en el HOGAR"}]},{"@type":"WebSite","@id":"https:\/\/www.ozono21.com\/blog\/#website","url":"https:\/\/www.ozono21.com\/blog\/","name":"Blog Ozono21","description":" - Blog Ozono21","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ozono21.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/09b7d3e74b7c4469cd705f2b20bca17c","name":"INVESTIGACION Ozono21","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/eea303d14545d78db33215a13da7c9b8ca3429e072b4b1c115d30546d8d679d6?s=96&d=mm&r=g","caption":"INVESTIGACION Ozono21"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/Agentes-que-causan-el-CANCER-en-el-hogar-e1454198372420.gif","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5221233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/users\/46969"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/comments?post=5221233"}],"version-history":[{"count":0,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5221233\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media\/5205410"}],"wp:attachment":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media?parent=5221233"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/categories?post=5221233"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/tags?post=5221233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}