{"id":5210018,"date":"2014-11-24T18:02:19","date_gmt":"2014-11-24T16:02:19","guid":{"rendered":"https:\/\/www.ozono21.com\/blog\/?p=5210018"},"modified":"2026-02-14T20:37:47","modified_gmt":"2026-02-14T18:37:47","slug":"grasas-trans-perder-memoria","status":"publish","type":"post","link":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/","title":{"rendered":"Grasas Trans demasiadas es perder memoria"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/11\/grasas-trans.jpg\" alt=\"grasas trans\" title=\"Grasas Trans\" width=\"202\" height=\"202\" style=\"margin: 0px 10px 0px 0px; cursor: hand; border: 0px;\"  class=\"alignleft\"  \/><a title=\"Ozono para Alimentos de Cocina. Nuestra COCINA es problem\u00e1tica y es fundamental en nuestra salud, ya que es donde guardamos los ALIMENTOS, los cocinamos y el agua que bebemos y utilizamos a la hora de cocinar\" href=\"https:\/\/www.ozono21.com\/sectores\/domesticos\/alimentos-cocina\/30\/\" target=\"_blank\" rel=\"noopener noreferrer\">Grasas Trans demasiadas es perder memoria <\/p>\n<p>Demasiadas &#8216;grasas trans&#8217; nos hacen perder la memoria<BR\/><BR\/>Estas sustancias favorecen la oxidaci\u00f3n celular y limitan su capacidad energ\u00e9tica.<BR\/><BR\/>Mayor riesgo de enfermedad cardiovascular, hipertensi\u00f3n, diabetes, obesidad&#8230; y ahora deterioro cognitivo.<\/A><\/strong><\/h2>\n<p><\/P><\/p>\n<p>FUENTE | ABC Peri\u00f3dico Electr\u00f3nico S.A.  (19\/11\/2014)<br \/>Autor:   E. Ortega<\/p>\n<p style=\"text-align: justify;\"><strong>Un elevado consumo de grasas trans parece estar vinculado a una peor memoria, seg\u00fan un estudio presentado en las Sesiones Cient\u00edficas de la American Heart Association 2014.<\/strong> Tras analizar a 1.000 hombres sanos y activos, el trabajo ha visto que aquellos consumieron mayores cantidades de grasas trans mostraron un peor rendimiento en una prueba de memoria. Adem\u00e1s, la asociaci\u00f3n se mantuvo incluso despu\u00e9s de tener en cuenta factores como la edad, la educaci\u00f3n, el grupo \u00e9tnico y la depresi\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><big><strong><a target=\"_blank\" title=\"La mejor inversi\u00f3n es usar las propiedades y virtudes, que nos ofrece un generador de OZONO. APLICACIONES Y USO DEL OZONO EN LA INDUSTRIA ALIMENTARIA\" href=\"https:\/\/www.ozono21.com\/sectores\/industriales\/industria-alimentaria\/18\/\" rel=\"noopener noreferrer\">\u00abDesde el punto de vista de la salud, el consumo de grasas trans se ha relacionado con el sobrepeso y la enfermedad card\u00edaca.<\/A><\/strong><\/big> <strong>Yo les digo a mis pacientes que mientras que las grasas trans aumentan la vida \u00fatil de los alimentos, reducen la vida de las personas\u00bb, se\u00f1al\u00f3 Beatrice Golomb,<\/strong> autora principal y profesora en la Universidad de California-San Diego (EE.UU.). <\/p>\n<p style=\"text-align: justify;\">El equipo de Golomb ha estudiado un grupo de adultos que no hab\u00edan sido diagnosticados con enfermedades del coraz\u00f3n. Todos los participantes completaron un cuestionario diet\u00e9tico, a partir del cual se estim\u00f3 el consumo de grasas trans de los participantes. Para evaluar la memoria, los voluntarios realizaci\u00f3n una prueba de memoria, que consist\u00eda en que, tras mostrarles serie de 104 tarjetas, \u00e9stos ten\u00edan que indicar si cada palabra era nueva o estaba duplicada.<\/p>\n<p style=\"text-align: justify;\"><big><strong><a target=\"_blank\" title=\"La mejor inversi\u00f3n es usar las propiedades y virtudes, que nos ofrece un generador de OZONO. Conseguimos: \u2022 SALUD \u2022 BIENESTAR \u2022 BELLEZA. OZONO GARANTIA de SALUD y AUMENTO de la ENERGIA VITAL\" href=\"https:\/\/www.ozono21.com\/sectores\/empresariales\/salud-bienestar\/7\/\" rel=\"noopener noreferrer\">MENOS PALABRAS<\/A><\/strong><\/big><\/p>\n<p style=\"text-align: justify;\"><strong>Los resultados mostraron que, entre los varones menores de 45 a\u00f1os de edad, aquellos que com\u00edan mayor cantidad ten\u00edan un peor rendimiento en la prueba de memoria.<\/strong> De hecho, cada gramo adicional de consumo diario de grasas trans se asociaba con una p\u00e9rdida de 0,76 palabras en los test de memoria.<\/p>\n<p style=\"text-align: justify;\">As\u00ed por <strong>ejemplo, aquellos que consum\u00edan la mayor cantidad recordaban 11 palabras menos (una reducci\u00f3n de m\u00e1s del 10%) que los adultos que com\u00edan menos.<\/strong> (El n\u00famero medio de palabras recordadas correctamente era 86). <\/p>\n<p style=\"text-align: justify;\">\u00abSabemos <strong>-apunta Golomb-<\/strong> que los alimentos tienen diferentes efectos sobre el estr\u00e9s oxidativo y la energ\u00eda de la c\u00e9lula\u00bb. As\u00ed, recuerda, en un estudio anterior <big><strong><a title=\"Generadores de Ozono21. SALUD de las personas y se puede UTILIZAR en el Hogar, Oficinas, Restaurantes, Hoteles, Hospitales e Industria\" href=\"https:\/\/www.ozono21.com\/productos-ozono\" target=\"_blank\" rel=\"noopener noreferrer\">\u00abencontramos el chocolate, que es rico en antioxidantes y tiene un impacto positivo en la energ\u00eda celular, est\u00e1 vinculado a una mejor memoria de palabras en adultos j\u00f3venes y de mediana edad. Ahora en este estudio, se analiz\u00f3 si las grasas trans, que son prooxidante y est\u00e1n vinculadas de manera adversa a la energ\u00eda celular, pueden mostrar el efecto contrario. Y lo hicieron\u00bb.<\/a><\/strong><\/big><\/p>\n<p style=\"text-align: justify;\"><big><strong><a title=\"AGRICULTURA PROCESO con OZONO es adecuado en la agricultura. DESINFECCION de los microorganismos SIN los productos TOXICOS QUIMICOS (herbicidas, fungicidas, pesticidas, etc). PROCESO con OZONO tanto en el AGUA de el procesamiento de productos o en el AIRE donde se almacenan todos los productos\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/agricultura-proceso-ozono\/425\/\" target=\"_blank\" rel=\"noopener noreferrer\">BAJO SOSPECHA<\/A><\/strong><\/big><\/p>\n<p style=\"text-align: justify;\"><big><strong><a title=\"AGRICULTURA PROCESO con OZONO es adecuado en la agricultura. DESINFECCION de los microorganismos SIN los productos TOXICOS QUIMICOS (herbicidas, fungicidas, pesticidas, etc). PROCESO con OZONO tanto en el AGUA de el procesamiento de productos o en el AIRE donde se almacenan todos los productos\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/agricultura-proceso-ozono\/425\/\" target=\"_blank\" rel=\"noopener noreferrer\">Las grasas trans industriales son productos producidos artificialmente para convertir los aceites l\u00edquidos en s\u00f3lidos a temperatura ambiente y extender la vida \u00fatil de los alimentos. Se pueden encontrar en margarinas, comidas r\u00e1pidas, boller\u00eda industrial, bocadillos, pizza congelada, cremas para caf\u00e9 y algunas pastas refrigeradas.<\/a><\/strong><\/big><\/P><\/p>\n<p style=\"text-align: justify;\"><strong>En EE.UU., la Administraci\u00f3n de Alimentos y Drogas (FDA) est\u00e1 adoptando nuevas medidas para reducir la cantidad de grasas trans artificiales en los alimentos. En Europa, solo unos pocos pa\u00edses -Dinamarca, Austria, Suiza e Islandia &#8211;<\/strong> han obligado a la industria a limitar la cantidad de \u00e1cidos grasos trans utilizada en los alimentos, pero la mayor\u00eda de los pa\u00edses todav\u00eda dependen de que los fabricantes de alimentos reduzcan voluntariamente el contenido de \u00e1cidos grasos trans de sus productos. <big><strong><a target=\"_blank\" title=\"La mejor inversi\u00f3n es usar las propiedades y virtudes, que nos ofrece un generador de OZONO. APLICACIONES Y USO DEL OZONO EN LA INDUSTRIA ALIMENTARIA\" href=\"https:\/\/www.ozono21.com\/sectores\/industriales\/industria-alimentaria\/18\/\" rel=\"noopener noreferrer\">La \u00fanica forma de limitar el consumo de \u00e1cidos grasos trans es exigiendo un etiquetado m\u00e1s claro de los alimentos.<\/A><\/strong><\/big><\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Actualidad ACCION del OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/accion-del-ozono\/423\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Noticias-Relacionadas.png\" alt=\"Actualidad ACCION del OZONO\" width=\"600\" height=\"25\" border=\"0\" \/><\/a><\/strong>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td width=\"150\" height=\"150\" align=\"center\"><a title=\"Grasas Trans\" href=\"https:\/\/www.ozono21.com\/blog\/?s=Grasas+Trans\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/11\/grasas-trans.jpg\"  alt=\"Grasas Trans\" width=\"145\" height=\"145\" class=\"alignright size-full wp-image-5207224\"  style=\"margin: 10px 10px 10px 0px; cursor: hand; border: 0px;\" border=\"0\" \/><\/a><\/td>\n<td width=\"300\" height=\"150\" style=\"text-align: left; vertical-align: middle;\"><big><strong><a title=\"Grasas Trans\" href=\"https:\/\/www.ozono21.com\/blog\/?s=Grasas+Trans\" target=\"_blank\" rel=\"noopener noreferrer\">Grasas Trans<\/a><\/strong><\/big>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Videos YouTube\" target=\"_blank\" href=\"http:\/\/www.youtube.com\/user\/ozono21\/videos?sort=p&amp;view=0&amp;flow=grid\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Videos-Youtube.png\" alt=\"Videos Youtube\" width=\"600\" height=\"25\" border=\"0\" \/><\/a><\/strong>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/8mJRDV4g-fA\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5210018\" class=\"pvc_stats total_only  \" data-element-id=\"5210018\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Grasas Trans demasiadas es perder memoria Demasiadas &#8216;grasas trans&#8217; nos hacen perder la memoriaEstas sustancias favorecen la oxidaci\u00f3n celular y limitan su capacidad energ\u00e9tica.Mayor riesgo de enfermedad cardiovascular, hipertensi\u00f3n, diabetes, obesidad&#8230; y ahora deterioro cognitivo. FUENTE | ABC Peri\u00f3dico Electr\u00f3nico &hellip; <a href=\"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5210018\" class=\"pvc_stats total_only  \" data-element-id=\"5210018\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":5210016,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[24,21,81],"class_list":["post-5210018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salud","tag-alimentos-2","tag-salud-2","tag-sociedad"],"a3_pvc":{"activated":true,"total_views":4045,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grasas Trans demasiadas es perder memoria<\/title>\n<meta name=\"description\" content=\"Demasiadas grasas trans hacen perder memoria MAS riesgo enfermedad cardiovascular, hipertensi\u00f3n, diabetes, obesidad, deterioro cognitivo, ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grasas Trans demasiadas es perder memoria\" \/>\n<meta property=\"og:description\" content=\"Demasiadas grasas trans hacen perder memoria MAS riesgo enfermedad cardiovascular, hipertensi\u00f3n, diabetes, obesidad, deterioro cognitivo, ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/\" \/>\n<meta property=\"og:site_name\" content=\"- Blog Ozono21\" \/>\n<meta property=\"article:published_time\" content=\"2014-11-24T16:02:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-14T18:37:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/11\/grasas-trans-e1455188364579.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"240\" \/>\n\t<meta property=\"og:image:height\" content=\"180\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"INVESTIGACION Ozono21\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"INVESTIGACION Ozono21\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/salud\\\/grasas-trans-perder-memoria\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/salud\\\/grasas-trans-perder-memoria\\\/\"},\"author\":{\"name\":\"INVESTIGACION Ozono21\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\"},\"headline\":\"Grasas Trans demasiadas es perder memoria\",\"datePublished\":\"2014-11-24T16:02:19+00:00\",\"dateModified\":\"2026-02-14T18:37:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/salud\\\/grasas-trans-perder-memoria\\\/\"},\"wordCount\":629,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/salud\\\/grasas-trans-perder-memoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/grasas-trans-e1455188364579.jpg\",\"keywords\":[\"Alimentos\",\"Salud\",\"Sociedad\"],\"articleSection\":[\"Salud\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/salud\\\/grasas-trans-perder-memoria\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/salud\\\/grasas-trans-perder-memoria\\\/\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/salud\\\/grasas-trans-perder-memoria\\\/\",\"name\":\"Grasas Trans demasiadas es perder memoria\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/salud\\\/grasas-trans-perder-memoria\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/salud\\\/grasas-trans-perder-memoria\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/grasas-trans-e1455188364579.jpg\",\"datePublished\":\"2014-11-24T16:02:19+00:00\",\"dateModified\":\"2026-02-14T18:37:47+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\"},\"description\":\"Demasiadas grasas trans hacen perder memoria MAS riesgo enfermedad cardiovascular, hipertensi\u00f3n, diabetes, obesidad, deterioro cognitivo, ...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/salud\\\/grasas-trans-perder-memoria\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/salud\\\/grasas-trans-perder-memoria\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/salud\\\/grasas-trans-perder-memoria\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/grasas-trans-e1455188364579.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/grasas-trans-e1455188364579.jpg\",\"width\":240,\"height\":180},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/salud\\\/grasas-trans-perder-memoria\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grasas Trans demasiadas es perder memoria\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\",\"name\":\"Blog Ozono21\",\"description\":\" - Blog Ozono21\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\",\"name\":\"INVESTIGACION Ozono21\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"caption\":\"INVESTIGACION Ozono21\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grasas Trans demasiadas es perder memoria","description":"Demasiadas grasas trans hacen perder memoria MAS riesgo enfermedad cardiovascular, hipertensi\u00f3n, diabetes, obesidad, deterioro cognitivo, ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/","og_locale":"es_ES","og_type":"article","og_title":"Grasas Trans demasiadas es perder memoria","og_description":"Demasiadas grasas trans hacen perder memoria MAS riesgo enfermedad cardiovascular, hipertensi\u00f3n, diabetes, obesidad, deterioro cognitivo, ...","og_url":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/","og_site_name":"- Blog Ozono21","article_published_time":"2014-11-24T16:02:19+00:00","article_modified_time":"2026-02-14T18:37:47+00:00","og_image":[{"width":240,"height":180,"url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/11\/grasas-trans-e1455188364579.jpg","type":"image\/jpeg"}],"author":"INVESTIGACION Ozono21","twitter_misc":{"Escrito por":"INVESTIGACION Ozono21","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/#article","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/"},"author":{"name":"INVESTIGACION Ozono21","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12"},"headline":"Grasas Trans demasiadas es perder memoria","datePublished":"2014-11-24T16:02:19+00:00","dateModified":"2026-02-14T18:37:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/"},"wordCount":629,"commentCount":0,"image":{"@id":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/11\/grasas-trans-e1455188364579.jpg","keywords":["Alimentos","Salud","Sociedad"],"articleSection":["Salud"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/","url":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/","name":"Grasas Trans demasiadas es perder memoria","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/#primaryimage"},"image":{"@id":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/11\/grasas-trans-e1455188364579.jpg","datePublished":"2014-11-24T16:02:19+00:00","dateModified":"2026-02-14T18:37:47+00:00","author":{"@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12"},"description":"Demasiadas grasas trans hacen perder memoria MAS riesgo enfermedad cardiovascular, hipertensi\u00f3n, diabetes, obesidad, deterioro cognitivo, ...","breadcrumb":{"@id":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/#primaryimage","url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/11\/grasas-trans-e1455188364579.jpg","contentUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/11\/grasas-trans-e1455188364579.jpg","width":240,"height":180},{"@type":"BreadcrumbList","@id":"https:\/\/www.ozono21.com\/blog\/salud\/grasas-trans-perder-memoria\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ozono21.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Grasas Trans demasiadas es perder memoria"}]},{"@type":"WebSite","@id":"https:\/\/www.ozono21.com\/blog\/#website","url":"https:\/\/www.ozono21.com\/blog\/","name":"Blog Ozono21","description":" - Blog Ozono21","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ozono21.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12","name":"INVESTIGACION Ozono21","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","caption":"INVESTIGACION Ozono21"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/11\/grasas-trans-e1455188364579.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5210018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/comments?post=5210018"}],"version-history":[{"count":0,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5210018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media\/5210016"}],"wp:attachment":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media?parent=5210018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/categories?post=5210018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/tags?post=5210018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}