{"id":5205311,"date":"2014-04-02T02:32:42","date_gmt":"2014-04-02T00:32:42","guid":{"rendered":"https:\/\/www.ozono21.com\/blog\/?p=5205311"},"modified":"2026-03-25T15:50:06","modified_gmt":"2026-03-25T13:50:06","slug":"ozono-bacterias-virus-y-patogenos","status":"publish","type":"post","link":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/","title":{"rendered":"BACTERIAS, VIRUS y PAT\u00f3GENOS, efectos del OZONO"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/04\/BACTERIAS-que-son-oxidados-matados-eliminados-por-OZONO.jpg\" alt=\"BACTERIAS\" width=\"200\" height=\"140\"  border=\"0\" class=\"alignright\" style=\"margin: 10px 0px 0px 10px; border: 0px;\" \/><a title=\"Efecto del OZONO en las Bacterias \" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/efecto-del-ozono-bacterias\/373\/\" rel=\"noopener noreferrer\">OZONO vs BACTERIAS <\/a><\/strong><\/H2><\/p>\n<p style=\"text-align: justify;\"><BIG><strong><a title=\"OZONO desinfecci\u00f3n y eliminaci\u00f3n de Bacterias y Virus\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/sectores-pagina\/empresariales\/desinfeccion-limpieza\/3\/\" rel=\"noopener noreferrer\"> BACTERIAS son microsc&oacute;picos, unicelulares criaturas que tienen una estructura primitiva.<\/a><\/strong><\/BIG><\/P> <\/p>\n<p style=\"text-align: justify;\">El cuerpo de las bacterias se sella por una membrana relativamente s&oacute;lida de c&eacute;lulas.<\/P> <\/p>\n<p style=\"text-align: justify;\">El <strong><a title=\"ACCIONES DEL OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/bacterias-eliminadas-ozono\/424\/\" rel=\"noopener noreferrer\">OZONO<\/a><\/strong> interfiere&nbsp;en el metabolismo de la&nbsp;BACTERIA en las c&eacute;lulas,&nbsp;a trav&eacute;s de la inhibici&oacute;n y el bloqueo de la operaci&oacute;n del sistema de control enzim&aacute;tica. Una cantidad suficiente de <strong><a title=\"ACCIONES DEL OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/bacterias-eliminadas-ozono\/424\/\" rel=\"noopener noreferrer\">OZONO<\/a><\/strong> rompe la membrana celular y esto conduce a la destrucci&oacute;n de las bacterias .<\/p>\n<p style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\"><strong><a title=\"ACCIONES del OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/acciones-del-ozono\/102\/\" rel=\"noopener noreferrer\">OZONO vs VIRUS<\/a><\/strong><\/H2><\/p>\n<p style=\"text-align: justify;\"><BIG><strong><a title=\"OZONO desinfecci\u00f3n y eliminaci\u00f3n de Bacterias y Virus\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/sectores-pagina\/empresariales\/desinfeccion-limpieza\/3\/\" rel=\"noopener noreferrer\">Los VIRUS son part&iacute;culas peque&ntilde;as e independientes, construidos de cristales y macromol&eacute;culas, a diferencia de las bacterias, se multiplican s&oacute;lo dentro de la c&eacute;lula hu&eacute;sped.<\/a><\/strong><\/BIG> Se transforman las prote&iacute;nas de la c&eacute;lula hu&eacute;sped en sus propias prote&iacute;nas del VIRUS. El <strong><a title=\"ACCIONES DEL OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/acciones-del-ozono\/102\/\" rel=\"noopener noreferrer\">OZONO<\/a><\/strong> destruye los VIRUS por distribuirse a trav&eacute;s de la capa de la prote&iacute;na en el n&uacute;cleo de &aacute;cido nucleico, que resulta en da&ntilde;o del ARN viral. A altas concentraciones, el <strong><a title=\"ACCIONES DEL OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/acciones-del-ozono\/102\/\" rel=\"noopener noreferrer\">OZONO<\/a><\/strong> destruye la c&aacute;pside, o capa exterior&nbsp;por la oxidaci&oacute;n de las&nbsp;prote&iacute;nas para el ADN (&aacute;cido desoxirribonucleico) o ARN (&aacute;cido ribonucleico), por lo que&nbsp;las estructuras de los microorganismos se ven afectados, destruidos y en definitiva eliminados.<\/p>\n<p><strong>TABLA de ELIMINACI&Oacute;N de PAT&oacute;GENOS con OZONO<\/strong><\/p>\n<table border=\"1\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" style=\"text-align: center;\"><strong><span style=\"COLOR: #ffffff\">Pat&oacute;geno<\/span><\/strong><\/td>\n<td bgcolor=\"#3b7cff\" style=\"text-align: center;\"><strong><span style=\"COLOR: #ffffff\">Dosis de OZONO<\/span><\/strong><\/td>\n<\/tr>\n<tr>\n<td>Aspergillus N&iacute;ger (Monte Negro)<\/td>\n<td>Destruido por 1,5 a 2 mg \/ litro<\/td>\n<\/tr>\n<tr>\n<td>Las bacterias Bacillus<\/td>\n<td>Destruido por 0,2 mg \/ litro en 30 segundos<\/td>\n<\/tr>\n<tr>\n<td>Bacillus anthracis (&aacute;ntrax causas en las ovejas, vacas y cerdos. Tambi&eacute;n es un pat&oacute;geno humano)<\/td>\n<td>El ozono susceptibles<\/td>\n<\/tr>\n<tr>\n<td>Bacillus cereus<\/td>\n<td>99% de destrucci&oacute;n despu&eacute;s de 5-min a 0,12 mg \/ litro en agua <\/td>\n<\/tr>\n<tr>\n<td>B. cereus (esporas) <\/td>\n<td>&nbsp; <\/td>\n<\/tr>\n<tr>\n<td>Bacillus subtilis<\/td>\n<td>90% de reducci&oacute;n en 0,10-PPM durante 33 minutos<\/td>\n<\/tr>\n<tr>\n<td>Bacteri&oacute;fago f2<\/td>\n<td>99,99% de destrucci&oacute;n en 0,41 mg \/ l para 10 segundos en el agua<\/td>\n<\/tr>\n<tr>\n<td>Botrytis cinerea<\/td>\n<td>3,8 mg \/ l durante 2 minutos <\/td>\n<\/tr>\n<tr>\n<td>Candida bacterias <\/td>\n<td>El ozono susceptibles<\/td>\n<\/tr>\n<tr>\n<td>Clavibacter michiganense&gt;<\/td>\n<td>99,99% de destrucci&oacute;n a 1,1 mg \/ l durante 5 minutos <\/td>\n<\/tr>\n<tr>\n<td>Cladosporium<\/td>\n<td>90% de reducci&oacute;n en 0.10 PPM de 12.1 minutos <\/td>\n<\/tr>\n<tr>\n<td>Las bacterias Clostridium<\/td>\n<td>El ozono susceptibles<\/td>\n<\/tr>\n<tr>\n<td>Las esporas del Clostridium botulinum. Su toxina paraliza el sistema nervioso central, siendo un veneno multipliquen en los alimentos y las comidas.<\/td>\n<td>0,4 a 0,5 mg \/ litro valor umbral<\/td>\n<\/tr>\n<tr>\n<td>El virus de Coxsackie A9<\/td>\n<td>95% de la destrucci&oacute;n a 0,035 mg \/ litro para 10 segundos en el agua <\/td>\n<\/tr>\n<tr>\n<td>Coxsackie B5 Virus<\/td>\n<td>99,99% la destrucci&oacute;n de 0,4 mg \/ litro de 2,5 minutos en los lodos de efluentes <\/td>\n<\/tr>\n<tr>\n<td>La difteria pat&oacute;genos<\/td>\n<td>Destruido por 1,5 a 2 mg \/ litro<\/td>\n<\/tr>\n<tr>\n<td>Eberth (Bacillus abdomanalis tifus).Se propaga normalmente por una infecci&oacute;n acuosa y las causas de la fiebre tifoidea.<\/td>\n<td>Destruido por 1,5 a 2 mg \/ litro<\/td>\n<\/tr>\n<tr>\n<td>Virus Echo 29: El virus m&aacute;s sensible al ozono. <\/td>\n<td>Despu&eacute;s de un tiempo de contacto de 1 minuto a 1 mg \/ l de ozono, 99,999% muertos.<\/td>\n<\/tr>\n<tr>\n<td>Virus ent&eacute;ricos<\/td>\n<td>95% de la destrucci&oacute;n de 4,1 mg \/ litro durante 29 minutos en agua residual cruda <\/td>\n<\/tr>\n<tr>\n<td>La bacteria Escherichia coli (de heces)<\/td>\n<td>Destruido por 0,2 mg \/ litro en 30 segundos en el aire <\/td>\n<\/tr>\n<tr>\n<td>E-coli (en agua limpia) <\/td>\n<td>99,99% la destrucci&oacute;n de 0,25 mg \/ l para 1,6 minutos <\/td>\n<\/tr>\n<tr>\n<td>E-coli (en las aguas residuales)<\/td>\n<td>99,9% de la destrucci&oacute;n de 2,2 mg \/ litro durante 19 minutos <\/td>\n<\/tr>\n<tr>\n<td>Encefalomiocarditis Virus <\/td>\n<td>Destruir a nivel cero en menos de 30 segundos con 0,1 a 0,8 mg \/ litro<\/td>\n<\/tr>\n<tr>\n<td>Las bacterias Quistes Endamoebic<\/td>\n<td>El ozono susceptibles<\/td>\n<\/tr>\n<tr>\n<td>Enterovirus Virus <\/td>\n<td>Destruir a nivel cero en menos de 30 segundos con 0,1 a 0,8 mg \/ litro<\/td>\n<\/tr>\n<tr>\n<td>Fusarium oxysporum lycopersici<\/td>\n<td>1,1 mg \/ litro durante 10 minutos <\/td>\n<\/tr>\n<tr>\n<td>Fusarium oxysporum f.sp. melonogea <\/td>\n<td>99,99% de destrucci&oacute;n a 1,1 mg \/ litro durante 20 minutos <\/td>\n<\/tr>\n<tr>\n<td>GDVII Virus<\/td>\n<td>Destruir a nivel cero en menos de 30 segundos con 0,1 a 0,8 mg \/ litro<\/td>\n<\/tr>\n<tr>\n<td>Virus de la hepatitis A <\/td>\n<td>99,5% de reducci&oacute;n en 0,25 mg \/ litro durante 2-segundos en un tamp&oacute;n fosfato <\/td>\n<\/tr>\n<tr>\n<td>Virus del herpes <\/td>\n<td>Destruir a nivel cero en menos de 30 segundos, con 0,1 a 0,8 mg \/ litro<\/td>\n<\/tr>\n<tr>\n<td>Virus de la gripe <\/td>\n<td>0,4 a 0,5 mg \/ litro <\/td>\n<\/tr>\n<tr>\n<td>Klebs-Loffler Bacillus <\/td>\n<td>Destruido por 1,5 a 2 mg \/ litro <\/td>\n<\/tr>\n<tr>\n<td>Legionella pneumophila <\/td>\n<td>99,99% la destrucci&oacute;n de 0,32 mg \/ litro durante 20 minutos en agua destilada <\/td>\n<\/tr>\n<tr>\n<td>Basidiomicetos luminiscentes (especies que no tienen pigmento melanina)<\/td>\n<td>Destruido en 10 minutos a 100 PPM <\/td>\n<\/tr>\n<tr>\n<td>Mucor piriforme <\/td>\n<td>3,8 mg \/ litro durante 2 minutos <\/td>\n<\/tr>\n<tr>\n<td>Mycobacterium avium <\/td>\n<td>99,9% con un valor de CT de 0,17 en agua<\/td>\n<\/tr>\n<tr>\n<td>Mycobacterium foruitum <\/td>\n<td>90% de la destrucci&oacute;n a 0,25 mg \/ litro de 1,6 minutos en el agua <\/td>\n<\/tr>\n<tr>\n<td>Las bacterias Penicillium <\/td>\n<td>El ozono susceptibles <\/td>\n<\/tr>\n<tr>\n<td>Phytophthora parasitica <\/td>\n<td>3,8 mg \/ litro durante 2 minutos <\/td>\n<\/tr>\n<tr>\n<td>Virus de la poliomielitis <\/td>\n<td>Mata a un 99,99% con 0,3 a 0,4 mg \/ litro en 3-4 minutos <\/td>\n<\/tr>\n<tr>\n<td>Poliovirus tipo 1 <\/td>\n<td>99,5% de la destrucci&oacute;n a 0,25 mg \/ litro de 1,6 minutos en el agua <\/td>\n<\/tr>\n<tr>\n<td>Las bacterias del g&eacute;nero Proteus <\/td>\n<td>Muy susceptible <\/td>\n<\/tr>\n<tr>\n<td>Las bacterias Pseudomonas <\/td>\n<td>Muy susceptible <\/td>\n<\/tr>\n<tr>\n<td>Bacterias Salmonella <\/td>\n<td>Destruir a nivel cero en menos de 30 segundos con 0,1 a 0,8 mg \/ litro <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>* 1 mg \/ litro = 1 ppm <\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Actualidad ACCION del OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/accion-del-ozono\/423\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Noticias-Relacionadas.png\" alt=\"Noticias Relacionadas\" width=\"600\" height=\"25\" style=\"margin: 0px 0px 0px 0px; cursor: hand; border: 0px;\"><\/a><\/strong>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><big><\/p>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td height=\"150\" width=\"150\" style=\"text-align: left; vertical-align: middle;\"><a title=\"Efecto del OZONO en las Bacterias \" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/efecto-del-ozono-bacterias\/373\/\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"Efecto del OZONO en las Bacterias \" width=\"129\" height=\"101\"  style=\"margin: 10px 10px 0px 50px; cursor: hand; border: 0px;\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/08\/ozono21_80_36.jpg\" \/><\/a><\/td>\n<td height=\"150\" width=\"300\" style=\"text-align: left; vertical-align: middle;\"><strong><a title=\"Efecto del OZONO en las Bacterias \" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/efecto-del-ozono-bacterias\/373\/\" rel=\"noopener noreferrer\">Efecto del OZONO en las Bacterias<\/a><\/strong> <\/td>\n<\/tr>\n<tr>\n<td height=\"150\" width=\"150\" align=\"center\"><a title=\"El ozono en Acci&oacute;n contra los VIRUS\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/el-ozono-accion-contra-virus\/378\/\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"El ozono en Acci&oacute;n contra los VIRUS\" width=\"131\" height=\"141\"  style=\"margin: 10px 10px 0px 50px; cursor: hand; border: 0px;\"  src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/07\/El-ozono-en-Acci\u00f3n-contra-los-VIRUS.jpg\" \/><\/a><\/td>\n<td height=\"150\" width=\"300\" style=\"text-align: left; vertical-align: middle;\"><strong><a title=\"El ozono en Acci&oacute;n contra los VIRUS\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/el-ozono-accion-contra-virus\/378\/\" rel=\"noopener noreferrer\">El ozono en Acci&oacute;n contra los VIRUS<\/a><\/strong> <\/td>\n<\/tr>\n<tr>\n<td height=\"150\" width=\"150\" align=\"center\"><a title=\" BACTERIAS que son oxidados matados eliminados por OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/organismos-que-son-oxidados-matados-eliminados-por-ozono\/67\/\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/08\/Bacterias-eliminadas-con-OZONO.jpg\" alt=\" BACTERIAS que son oxidados matados eliminados por OZONO\" width=\"140\" height=\"130\"   style=\"margin: 10px 10px 0px 50px; cursor: hand; border: 0px;\"  \/><\/a><\/td>\n<td height=\"150\" width=\"300\" style=\"text-align: left; vertical-align: middle;\"><strong><a title=\" BACTERIAS y VIRUS que son oxidados matados eliminados por OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/organismos-que-son-oxidados-matados-eliminados-por-ozono\/67\/\" rel=\"noopener noreferrer\"> BACTERIAS que son oxidados matados eliminados por OZONO<\/a><\/strong> <\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><\/big><\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Videos YouTube\" target=\"_blank\" href=\"http:\/\/www.youtube.com\/user\/ozono21\/videos?sort=p&amp;view=0&amp;flow=grid\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Videos-Youtube.png\" alt=\"Videos Youtube\" width=\"600\" height=\"25\" style=\"margin: 0px 0px 0px 0px; cursor: hand; border: 0px;\"><\/a><\/strong>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: center\"><iframe loading=\"lazy\" width=\"651\" height=\"488\" src=\"https:\/\/www.youtube.com\/embed\/rzeWAeUnGLA\" title=\"C\u00f3mo las bacterias causan enfermedades\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p style=\"TEXT-ALIGN: center\"><iframe loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/R5_qeyni9iI\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5205311\" class=\"pvc_stats total_only  \" data-element-id=\"5205311\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>OZONO vs BACTERIAS BACTERIAS son microsc&oacute;picos, unicelulares criaturas que tienen una estructura primitiva. El cuerpo de las bacterias se sella por una membrana relativamente s&oacute;lida de c&eacute;lulas. El OZONO interfiere&nbsp;en el metabolismo de la&nbsp;BACTERIA en las c&eacute;lulas,&nbsp;a trav&eacute;s de la &hellip; <a href=\"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5205311\" class=\"pvc_stats total_only  \" data-element-id=\"5205311\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":5212267,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[41,5,16,7,15,26],"tags":[19,70,21,36,32,29],"class_list":["post-5205311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualidad-ozono","category-bacterias","category-germenes","category-salud","category-virus","category-vital-aire-agua-ozono21","tag-bacterias-2","tag-germenes","tag-salud-2","tag-toxinas-2","tag-videos-salud-2","tag-virus-2"],"a3_pvc":{"activated":true,"total_views":4433,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bacterias, Virus y PAT\u00f3GENOS, efectos del Ozono<\/title>\n<meta name=\"description\" content=\"BACTERIAS, VIRUS y PAT\u00f3GENOS, efectos del OZONO. Gracias a el OZONO se rompe la membrana celular y es la destrucci\u00f3n de bacterias, virus, ...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bacterias, Virus y PAT\u00f3GENOS, efectos del Ozono\" \/>\n<meta property=\"og:description\" content=\"BACTERIAS, VIRUS y PAT\u00f3GENOS, efectos del OZONO. Gracias a el OZONO se rompe la membrana celular y es la destrucci\u00f3n de bacterias, virus, ...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/\" \/>\n<meta property=\"og:site_name\" content=\"- Blog Ozono21\" \/>\n<meta property=\"article:published_time\" content=\"2014-04-02T00:32:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-25T13:50:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2006\/06\/BACTERIAS_1-e1456663929803.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"231\" \/>\n\t<meta property=\"og:image:height\" content=\"160\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"INVESTIGACION Ozono21\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"INVESTIGACION Ozono21\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/bacterias\\\/ozono-bacterias-virus-y-patogenos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/bacterias\\\/ozono-bacterias-virus-y-patogenos\\\/\"},\"author\":{\"name\":\"INVESTIGACION Ozono21\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\"},\"headline\":\"BACTERIAS, VIRUS y PAT\u00f3GENOS, efectos del OZONO\",\"datePublished\":\"2014-04-02T00:32:42+00:00\",\"dateModified\":\"2026-03-25T13:50:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/bacterias\\\/ozono-bacterias-virus-y-patogenos\\\/\"},\"wordCount\":856,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/bacterias\\\/ozono-bacterias-virus-y-patogenos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2006\\\/06\\\/BACTERIAS_1-e1456663929803.jpg\",\"keywords\":[\"Bacterias\",\"G\u00e9rmenes\",\"Salud\",\"Toxinas\",\"Videos SALUD\",\"Virus\"],\"articleSection\":[\"Actualidad de OZONO 21\",\"Bacterias\",\"G\u00e9rmenes\",\"Salud\",\"Virus\",\"VITAL AIRE &amp; AGUA OZONO21\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/bacterias\\\/ozono-bacterias-virus-y-patogenos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/bacterias\\\/ozono-bacterias-virus-y-patogenos\\\/\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/bacterias\\\/ozono-bacterias-virus-y-patogenos\\\/\",\"name\":\"Bacterias, Virus y PAT\u00f3GENOS, efectos del Ozono\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/bacterias\\\/ozono-bacterias-virus-y-patogenos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/bacterias\\\/ozono-bacterias-virus-y-patogenos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2006\\\/06\\\/BACTERIAS_1-e1456663929803.jpg\",\"datePublished\":\"2014-04-02T00:32:42+00:00\",\"dateModified\":\"2026-03-25T13:50:06+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\"},\"description\":\"BACTERIAS, VIRUS y PAT\u00f3GENOS, efectos del OZONO. Gracias a el OZONO se rompe la membrana celular y es la destrucci\u00f3n de bacterias, virus, ...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/bacterias\\\/ozono-bacterias-virus-y-patogenos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/bacterias\\\/ozono-bacterias-virus-y-patogenos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/bacterias\\\/ozono-bacterias-virus-y-patogenos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2006\\\/06\\\/BACTERIAS_1-e1456663929803.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2006\\\/06\\\/BACTERIAS_1-e1456663929803.jpg\",\"width\":231,\"height\":160},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/bacterias\\\/ozono-bacterias-virus-y-patogenos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BACTERIAS, VIRUS y PAT\u00f3GENOS, efectos del OZONO\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\",\"name\":\"Blog Ozono21\",\"description\":\" - Blog Ozono21\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\",\"name\":\"INVESTIGACION Ozono21\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"caption\":\"INVESTIGACION Ozono21\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bacterias, Virus y PAT\u00f3GENOS, efectos del Ozono","description":"BACTERIAS, VIRUS y PAT\u00f3GENOS, efectos del OZONO. Gracias a el OZONO se rompe la membrana celular y es la destrucci\u00f3n de bacterias, virus, ...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/","og_locale":"es_ES","og_type":"article","og_title":"Bacterias, Virus y PAT\u00f3GENOS, efectos del Ozono","og_description":"BACTERIAS, VIRUS y PAT\u00f3GENOS, efectos del OZONO. Gracias a el OZONO se rompe la membrana celular y es la destrucci\u00f3n de bacterias, virus, ...","og_url":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/","og_site_name":"- Blog Ozono21","article_published_time":"2014-04-02T00:32:42+00:00","article_modified_time":"2026-03-25T13:50:06+00:00","og_image":[{"width":231,"height":160,"url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2006\/06\/BACTERIAS_1-e1456663929803.jpg","type":"image\/jpeg"}],"author":"INVESTIGACION Ozono21","twitter_misc":{"Escrito por":"INVESTIGACION Ozono21","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/#article","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/"},"author":{"name":"INVESTIGACION Ozono21","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12"},"headline":"BACTERIAS, VIRUS y PAT\u00f3GENOS, efectos del OZONO","datePublished":"2014-04-02T00:32:42+00:00","dateModified":"2026-03-25T13:50:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/"},"wordCount":856,"commentCount":0,"image":{"@id":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2006\/06\/BACTERIAS_1-e1456663929803.jpg","keywords":["Bacterias","G\u00e9rmenes","Salud","Toxinas","Videos SALUD","Virus"],"articleSection":["Actualidad de OZONO 21","Bacterias","G\u00e9rmenes","Salud","Virus","VITAL AIRE &amp; AGUA OZONO21"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/","url":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/","name":"Bacterias, Virus y PAT\u00f3GENOS, efectos del Ozono","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/#primaryimage"},"image":{"@id":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2006\/06\/BACTERIAS_1-e1456663929803.jpg","datePublished":"2014-04-02T00:32:42+00:00","dateModified":"2026-03-25T13:50:06+00:00","author":{"@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12"},"description":"BACTERIAS, VIRUS y PAT\u00f3GENOS, efectos del OZONO. Gracias a el OZONO se rompe la membrana celular y es la destrucci\u00f3n de bacterias, virus, ...","breadcrumb":{"@id":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/#primaryimage","url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2006\/06\/BACTERIAS_1-e1456663929803.jpg","contentUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2006\/06\/BACTERIAS_1-e1456663929803.jpg","width":231,"height":160},{"@type":"BreadcrumbList","@id":"https:\/\/www.ozono21.com\/blog\/bacterias\/ozono-bacterias-virus-y-patogenos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ozono21.com\/blog\/"},{"@type":"ListItem","position":2,"name":"BACTERIAS, VIRUS y PAT\u00f3GENOS, efectos del OZONO"}]},{"@type":"WebSite","@id":"https:\/\/www.ozono21.com\/blog\/#website","url":"https:\/\/www.ozono21.com\/blog\/","name":"Blog Ozono21","description":" - Blog Ozono21","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ozono21.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12","name":"INVESTIGACION Ozono21","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","caption":"INVESTIGACION Ozono21"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2006\/06\/BACTERIAS_1-e1456663929803.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5205311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/comments?post=5205311"}],"version-history":[{"count":0,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5205311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media\/5212267"}],"wp:attachment":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media?parent=5205311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/categories?post=5205311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/tags?post=5205311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}