{"id":5196001,"date":"2012-05-28T17:46:30","date_gmt":"2012-05-28T15:46:30","guid":{"rendered":"https:\/\/www.ozono21.com\/blog\/?p=5196001"},"modified":"2026-02-11T21:39:27","modified_gmt":"2026-02-11T19:39:27","slug":"enfermedades-relacionadas-con-el-medio-ambiente","status":"publish","type":"post","link":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/","title":{"rendered":"1 de cada 5 europeos muere de enfermedades relacionadas con el medio ambiente"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\"  style=\"margin: 15px 5px 10px 0px; cursor: hand; border: 0px;\"  src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/05\/aire_contaminado.jpg\" alt=\" enfermedades relacionadas con el medio ambiente \" title=\" enfermedades relacionadas con el medio ambiente \"  width=\"250\" height=\"252\" \/><a title=\" OZONO  para el\n\nhogar\" href=\"https:\/\/www.ozono21.com\/sectores-pagina\/domesticos\/dormitorios-salones\/32\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Uno de cada cinco europeos muere de enfermedades relacionadas con el medio ambiente en el marco de los pa\u00edses que componen la Organizaci\u00f3n Mundial de la Salud (OMS), donde la carga de patolog\u00edas relacionadas con el entorno var\u00eda significativamente -entre un 14 y un 54%- en funci\u00f3n de la regi\u00f3n. A nivel nacional, la poblaci\u00f3n pobre est\u00e1 expuesta a riesgos ambientales hasta 5 veces m\u00e1s a menudo que los ricos. <\/a><\/strong><\/h2>\n<\/p>\n<p>Fuente: ambientum (15\/2\/2012)<\/p>\n<p style=\"text-align: justify;\">As\u00ed concluye el \u00faltimo informe sobre inequidades en salud medioambiental en Europa elaborado por el Centro para el Medio Ambiente y la Salud (ECEH, por sus siglas en ingl\u00e9s) de la Oficina Regional europea de la Organizaci\u00f3n Mundial de la Salud (OMS). Este centro elabora <strong>las gu\u00edas que orientan despu\u00e9s las pol\u00edticas sobre salud y medio ambiente<\/strong> que se ponen en pr\u00e1ctica en Europa y el resto del mundo.<\/p>\n<p style=\"text-align: justify;\">Cada europeo pierde unos 8,6 meses de esperanza de vida por respirar aire contaminado por encima de los niveles m\u00e1ximos recomendados por la OMS. Asimismo, el ruido relacionado con el tr\u00e1fico hace perder cerca de un mill\u00f3n de a\u00f1os de vida saludable al a\u00f1o a los occidentales. Adem\u00e1s, <strong>las viviendas inadecuadas generan unas 100.000 muertes<\/strong> al a\u00f1o s\u00f3lo en la regi\u00f3n europea de la OMS, seg\u00fan el ECEH.<\/p>\n<p style=\"text-align: justify;\">Su nuevo informe subraya que las mayores exposiciones a factores ambientales peligrosos las soportan los colectivos con menor poder socioecon\u00f3mico, por lo que ofrece, por primera vez, datos actualizados y m\u00e9todos para identificar las prioridades en las que se debe intervenir, a nivel nacional, para <strong>combatir las actuales inequidades<\/strong> en la distribuci\u00f3n de los riesgos medioambientales de salud.<\/p>\n<p style=\"text-align: justify;\">Por ejemplo, el documento resalta que, s\u00f3lo en la UE, <strong>cerca de 80 millones de personas viven en un relativo nivel de pobreza<\/strong>, con ingresos por debajo del 60 por ciento del nivel de ingresos medios de su pa\u00eds. Muchas de estas personas en casas h\u00famedas, sin calor suficiente y un equipamiento sanitario inadecuado.<\/p>\n<p><strong>Siete millones de pobres sin ba\u00f1o en casa<\/strong><\/p>\n<p style=\"text-align: justify;\">En los nuevos pa\u00edses de la UE, que los m\u00e1s pobres no cuenten con un ba\u00f1o o ducha en casa es 13 veces m\u00e1s frecuente que en los pa\u00edses m\u00e1s ricos. Casi <strong>siete millones de ciudadanos pobres<\/strong> tienen este problema en la Uni\u00f3n Europea a nivel global.<\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, unos 16 millones de personas que viven en relativa pobreza no pueden permitirse costear la calefacci\u00f3n en sus hogares en invierno. Similares resultados se han observado en relaci\u00f3n con la exposici\u00f3n al ruido del tr\u00e1fico y al humo de segunda mano, seg\u00fan se apunta<strong> en este informe del ECEH.<\/strong><\/p>\n<p style=\"text-align: justify;\">Gracias al respaldo econ\u00f3mico del Gobierno alem\u00e1n, el ECEH ampliar\u00e1 sus operaciones cuando <strong>se cumplen ahora diez a\u00f1os<\/strong> de la apertura de sus instalaciones, en Bonn (Alemania).<\/p>\n<p style=\"text-align: justify;\">Seg\u00fan ha se\u00f1alado este martes la directora para Europa de la OMS, Zsuzsanna Jakab, \u00abvivimos en un medio ambiente en constante cambio, que <strong>nos pide innovar en nuestro trabajo y adaptar nuestras estrategias<\/strong>\u00ab. \u00abPor ello -dice- agradecemos al Gobierno alem\u00e1n que respalde mejorar el trabajo sobre medio ambiente y salud, una prioridad para la OMS\u00bb.<\/p>\n<p style=\"text-align: justify;\">Por su parte, el ministro alem\u00e1n de Medio Ambiente, Conservaci\u00f3n de la Naturaleza y Seguridad Nuclear, Norbert R\u00f6ttgen, ha dicho que su pa\u00eds est\u00e1 incrementando su apoyo financiero a este centro europeo \u00abporque el ambiente tiene un gran impacto en la salud humana\u00bb. \u00abQueremos que <strong>la OMS sea a\u00fan m\u00e1s activa<\/strong> en este campo y apoye nuestras pol\u00edticas con an\u00e1lisis y recomendaciones\u00bb, se\u00f1ala.<\/p>\n<p style=\"text-align: justify;\">Para el ministro alem\u00e1n de Salud, Daniel Bahr, \u00abla protecci\u00f3n preventiva de la salud requiere que se act\u00fae hoy para que las pr\u00f3ximas generaciones puedan <strong>tener ma\u00f1ana un mundo saludable<\/strong>\u00ab. \u00abPara este fin, debemos contar con todos los actores para identificar medidas conjuntas y reforzar nuestros sistemas de salud. El centro ampliado de la OMS en Bonn es un importante paso en esta direcci\u00f3n\u00bb, concluye.<\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Acci&oacute;n del OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/accion-del-ozono\/423\/\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"Noticias Relacionadas\" width=\"600\" height=\"25\" src=\"\/blog\/wp-content\/uploads\/2014\/06\/Noticias-Relacionadas.png\" \/><\/a><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><big><\/p>\n<ul>\n<li><strong><a title=\"Los picos de contaminaci\u00f3n aumentan el riesgo de infarto\" href=\"https:\/\/www.ozono21.com\/blog\/salud\/los-picos-de-contaminacion-aumentan-el-riesgo-de-infarto\/\" target=\"_blank\" rel=\"noopener noreferrer\">Los picos de contaminaci\u00f3n aumentan el riesgo de infarto<\/a><\/strong><\/li>\n<li><strong><a title=\"Afrontar el reto mundial de garantizar un aire limpio\" href=\"https:\/\/www.ozono21.com\/blog\/bacterias\/afrontar-el-reto-mundial-de-garantizar-un-aire-limpio\/\" target=\"_blank\" rel=\"noopener noreferrer\">Afrontar el reto mundial de garantizar un aire limpio<\/a><\/strong><\/li>\n<li><strong><a title=\"Alerta global la exposici\u00f3n excesiva a radiaciones de m\u00f3viles, wi-fi y campos electromagn\u00e9ticos, puede provocar crisis de salud\" href=\"https:\/\/www.ozono21.com\/blog\/toxinas\/alerta-global-la-exposicion-excesiva-a-radiaciones-de-moviles-wi-fi-y-campos-electromagneticos-puede-provocar-crisis-de-salud\/\" target=\"_blank\" rel=\"noopener noreferrer\">Alerta global la exposici\u00f3n excesiva a radiaciones de m\u00f3viles, wi-fi y campos electromagn\u00e9ticos, puede provocar crisis de salud<\/a><\/strong><\/li>\n<li><strong><a title=\"El volumen de CO2 alcanza su nivel m\u00e1s alto de los \u00faltimos 800.000 a\u00f1os\" href=\"https:\/\/www.ozono21.com\/blog\/salud\/el-volumen-de-co2-alcanza-su-nivel-mas-alto-de-los-ultimos-800000-anos\/\" target=\"_blank\" rel=\"noopener noreferrer\">El volumen de CO2 alcanza su nivel m\u00e1s alto de los \u00faltimos 800.000 a\u00f1os<\/a><\/strong><\/li>\n<\/ul>\n<p><\/big><\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Videos YouTube\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/user\/ozono21\/videos?sort=p&amp;view=0&amp;flow=grid\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"Videos Youtube\" width=\"600\" height=\"25\" src=\"\/blog\/wp-content\/uploads\/2014\/06\/Videos-Youtube.png\" \/><\/a><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/xDCEz_-eiAY\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5196001\" class=\"pvc_stats total_only  \" data-element-id=\"5196001\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uno de cada cinco europeos muere de enfermedades relacionadas con el medio ambiente en el marco de los pa\u00edses que componen la Organizaci\u00f3n Mundial de la Salud (OMS), donde la carga de patolog\u00edas relacionadas con el entorno var\u00eda significativamente -entre &hellip; <a href=\"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5196001\" class=\"pvc_stats total_only  \" data-element-id=\"5196001\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":5196002,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[8,17,13],"tags":[20,74,21],"class_list":["post-5196001","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aire","category-contaminacion","category-medioambiente","tag-contaminacion-2","tag-medioambiente","tag-salud-2"],"a3_pvc":{"activated":true,"total_views":4016,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>enfermedades relacionadas con el medio ambiente<\/title>\n<meta name=\"description\" content=\"1 de cada 5 europeos muere de enfermedades relacionadas con el medio ambiente en el marco de los pa\u00edses que componen la OMS\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"enfermedades relacionadas con el medio ambiente\" \/>\n<meta property=\"og:description\" content=\"1 de cada 5 europeos muere de enfermedades relacionadas con el medio ambiente en el marco de los pa\u00edses que componen la OMS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/\" \/>\n<meta property=\"og:site_name\" content=\"- Blog Ozono21\" \/>\n<meta property=\"article:published_time\" content=\"2012-05-28T15:46:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-11T19:39:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/05\/aire_contaminado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"166\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"INVESTIGACION Ozono21\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"INVESTIGACION Ozono21\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/aire\\\/enfermedades-relacionadas-con-el-medio-ambiente\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/aire\\\/enfermedades-relacionadas-con-el-medio-ambiente\\\/\"},\"author\":{\"name\":\"INVESTIGACION Ozono21\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\"},\"headline\":\"1 de cada 5 europeos muere de enfermedades relacionadas con el medio ambiente\",\"datePublished\":\"2012-05-28T15:46:30+00:00\",\"dateModified\":\"2026-02-11T19:39:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/aire\\\/enfermedades-relacionadas-con-el-medio-ambiente\\\/\"},\"wordCount\":760,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/aire\\\/enfermedades-relacionadas-con-el-medio-ambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/aire_contaminado.jpg\",\"keywords\":[\"Contaminaci\u00f3n\",\"MedioAmbiente\",\"Salud\"],\"articleSection\":[\"Aire\",\"Contaminaci\u00f3n\",\"MedioAmbiente\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/aire\\\/enfermedades-relacionadas-con-el-medio-ambiente\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/aire\\\/enfermedades-relacionadas-con-el-medio-ambiente\\\/\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/aire\\\/enfermedades-relacionadas-con-el-medio-ambiente\\\/\",\"name\":\"enfermedades relacionadas con el medio ambiente\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/aire\\\/enfermedades-relacionadas-con-el-medio-ambiente\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/aire\\\/enfermedades-relacionadas-con-el-medio-ambiente\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/aire_contaminado.jpg\",\"datePublished\":\"2012-05-28T15:46:30+00:00\",\"dateModified\":\"2026-02-11T19:39:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\"},\"description\":\"1 de cada 5 europeos muere de enfermedades relacionadas con el medio ambiente en el marco de los pa\u00edses que componen la OMS\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/aire\\\/enfermedades-relacionadas-con-el-medio-ambiente\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/aire\\\/enfermedades-relacionadas-con-el-medio-ambiente\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/aire\\\/enfermedades-relacionadas-con-el-medio-ambiente\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/aire_contaminado.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/05\\\/aire_contaminado.jpg\",\"width\":250,\"height\":166},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/aire\\\/enfermedades-relacionadas-con-el-medio-ambiente\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"1 de cada 5 europeos muere de enfermedades relacionadas con el medio ambiente\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\",\"name\":\"Blog Ozono21\",\"description\":\" - Blog Ozono21\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\",\"name\":\"INVESTIGACION Ozono21\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"caption\":\"INVESTIGACION Ozono21\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"enfermedades relacionadas con el medio ambiente","description":"1 de cada 5 europeos muere de enfermedades relacionadas con el medio ambiente en el marco de los pa\u00edses que componen la OMS","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/","og_locale":"es_ES","og_type":"article","og_title":"enfermedades relacionadas con el medio ambiente","og_description":"1 de cada 5 europeos muere de enfermedades relacionadas con el medio ambiente en el marco de los pa\u00edses que componen la OMS","og_url":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/","og_site_name":"- Blog Ozono21","article_published_time":"2012-05-28T15:46:30+00:00","article_modified_time":"2026-02-11T19:39:27+00:00","og_image":[{"width":250,"height":166,"url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/05\/aire_contaminado.jpg","type":"image\/jpeg"}],"author":"INVESTIGACION Ozono21","twitter_misc":{"Escrito por":"INVESTIGACION Ozono21","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/#article","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/"},"author":{"name":"INVESTIGACION Ozono21","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12"},"headline":"1 de cada 5 europeos muere de enfermedades relacionadas con el medio ambiente","datePublished":"2012-05-28T15:46:30+00:00","dateModified":"2026-02-11T19:39:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/"},"wordCount":760,"commentCount":0,"image":{"@id":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/05\/aire_contaminado.jpg","keywords":["Contaminaci\u00f3n","MedioAmbiente","Salud"],"articleSection":["Aire","Contaminaci\u00f3n","MedioAmbiente"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/","url":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/","name":"enfermedades relacionadas con el medio ambiente","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/#primaryimage"},"image":{"@id":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/05\/aire_contaminado.jpg","datePublished":"2012-05-28T15:46:30+00:00","dateModified":"2026-02-11T19:39:27+00:00","author":{"@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12"},"description":"1 de cada 5 europeos muere de enfermedades relacionadas con el medio ambiente en el marco de los pa\u00edses que componen la OMS","breadcrumb":{"@id":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/#primaryimage","url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/05\/aire_contaminado.jpg","contentUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/05\/aire_contaminado.jpg","width":250,"height":166},{"@type":"BreadcrumbList","@id":"https:\/\/www.ozono21.com\/blog\/aire\/enfermedades-relacionadas-con-el-medio-ambiente\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ozono21.com\/blog\/"},{"@type":"ListItem","position":2,"name":"1 de cada 5 europeos muere de enfermedades relacionadas con el medio ambiente"}]},{"@type":"WebSite","@id":"https:\/\/www.ozono21.com\/blog\/#website","url":"https:\/\/www.ozono21.com\/blog\/","name":"Blog Ozono21","description":" - Blog Ozono21","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ozono21.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12","name":"INVESTIGACION Ozono21","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","caption":"INVESTIGACION Ozono21"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/05\/aire_contaminado.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5196001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/comments?post=5196001"}],"version-history":[{"count":0,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5196001\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media\/5196002"}],"wp:attachment":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media?parent=5196001"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/categories?post=5196001"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/tags?post=5196001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}