{"id":5195062,"date":"2012-04-21T15:01:56","date_gmt":"2012-04-21T13:01:56","guid":{"rendered":"https:\/\/www.ozono21.com\/blog\/?p=5195062"},"modified":"2026-01-22T19:43:41","modified_gmt":"2026-01-22T17:43:41","slug":"comida-saludable-fuera-de-casa","status":"publish","type":"post","link":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/","title":{"rendered":"La mitad de los pa\u00edses europeos carece de normas para garantizar comida saludable fuera de casa"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-5195063\" style=\"border: 0px;\" title=\"La mitad de los pa\u00edses europeos carece de normas para garantizar comida saludable fuera de casa\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/04\/vida-sana-comida-basura.jpg\" alt=\" comida saludable  \" width=\"252\" height=\"282\" \/><a title=\"Ozono21 Restaurantes y Hosteler\u00eda\" href=\"https:\/\/www.ozono21.com\/sectores-pagina\/empresariales\/hosteleria-restauracion\/13\/\" target=\"_blank\" rel=\"noopener noreferrer\"> Se ha comprobado que este tipo de alimentos tienen m\u00e1s grasa y sal, adem\u00e1s de menos vitaminas.<\/a><\/strong><\/h2>\n<\/p>\n<p style=\"text-align: justify;\"><strong><a title=\"Ozono21 Restaurantes y Hosteler\u00eda\" href=\"https:\/\/www.ozono21.com\/sectores-pagina\/empresariales\/hosteleria-restauracion\/13\/\/\" target=\"_blank\" rel=\"noopener noreferrer\"> La mitad de los pa\u00edses europeos carece de normas para garantizar la disponibilidad de comida saludable en los restaurantes, comedores o para comer en la calle, mientras que los que las tienen a menudo realizan un escaso seguimiento de su impacto. <\/a><\/strong><\/h3>\n<\/p>\n<p>Fuente: consumer (15 dic. 2011)<\/p>\n<p style=\"text-align: justify;\">Son las conclusiones del estudio realizado por el <strong>Antwerp Institute of Tropical Medicine y la Ghent University, en B\u00e9lgica, que piden a los pol\u00edticos buscar el equilibrio entre los intereses comerciales y la preservaci\u00f3n de la salud p\u00fablica.<\/strong> <\/p>\n<p style=\"text-align: justify;\">Una tercera parte de la poblaci\u00f3n belga mayor de 15 a\u00f1os consigue un cuarto de su energ\u00eda de comer fuera de casa, un n\u00famero incluso mayor en muchos pa\u00edses. <strong>De la revisi\u00f3n mundial realizada por Carl Lachat, investigador del Antwerp Institute of Tropical Medicine y de la Ghent University, se ha visto que, por norma, <big><a title=\"Ozono21 Alimentos y Cocina\" href=\"https:\/\/www.ozono21.com\/sectores-pagina\/domesticos\/alimentos-cocina\/30\/\" target=\"_blank\" rel=\"noopener noreferrer\">la comida que se consume fuera de casa <\/a><\/big>tiene m\u00e1s grasa y sal, adem\u00e1s de menos vitaminas. El consumo de frutas y verdura obtiene a\u00fan peores resultados. <\/strong><\/p>\n<p style=\"text-align: justify;\">Sin embargo, las autoridades de los diferentes pa\u00edses tienen poco poder sobre lo que se hace en la privacidad de las cocinas, excepto para garantizar la seguridad y trazabilidad de los ingredientes que se emplean. A pesar de ello, carecen de influencia sobre la oferta de restaurantes, comedores y otros proveedores comerciales de alimentos y de comidas. <strong>La mayor\u00eda de las pol\u00edticas se preocupan sobre el etiquetado de la comida, la formaci\u00f3n del personal o la publicidad. Pero la <big><a title=\"Ozono21 Industria Alimentaria\" href=\"https:\/\/www.ozono21.com\/sectores-pagina\/industriales\/industria-alimentaria\/18\/\" target=\"_blank\" rel=\"noopener noreferrer\">salubridad de los alimentos parece preocupar menos y si alg\u00fan pa\u00eds instaura normas para regularla<\/a><\/big>, por ejemplo; la de ofrecer comida saludable en los comedores escolares, casi no se controla o cumple. <\/strong><\/p>\n<p style=\"text-align: justify;\">Estos investigadores comprobaron que en un comedor de estudiantes que si se ofrece m\u00e1s verdura o frutas gratis, es posible conseguir que las personas coman mejor, incluso tras concluir la prueba. <strong>Tambi\u00e9n se pueden poner en pr\u00e1ctica medidas simples sobre las porciones, las calor\u00edas, las opciones o la informaci\u00f3n nutricional. <\/strong><\/p>\n<p style=\"text-align: justify;\">Lachat ha se\u00f1alado que <strong>el sector de los <big><a title=\"Ozono21 comida Saludable\" href=\"https:\/\/www.ozono21.com\/sectores-pagina\/empresariales\/galerias-alimentacion\/4\/\" target=\"_blank\" rel=\"noopener noreferrer\">catering ofrece claras oportunidades para mejorar la dieta<\/a><\/big>de los consumidores<\/strong>. Solo hace falta que las autoridades presten atenci\u00f3n a la composici\u00f3n de la comida que se oferta fuera de casa y se impliquen en este sector para mejorar el producto que ofrecen. <strong>\u00abFaltan medidas para garantizar la disponibilidad de comida saludable fuera de casa o para hacer que este sector sea m\u00e1s responsable\u00bb, ha indicado Lachat<\/strong>, para quien controlar lo que los ciudadanos comen fuera de casa, para hacer que sean alimentos m\u00e1s saludables, ofrece<strong> \u00abnuevas soluciones de salud p\u00fablica\u00bb. <\/strong><\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Acci&oacute;n del OZONO\" target=\"_blank\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/accion-del-ozono\/423\/\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"Noticias Relacionadas\" width=\"600\" height=\"25\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Noticias-Relacionadas.png\" \/><\/a><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><big><\/p>\n<ul>\n<li><strong><a title=\"Seguridad alimentaria en cocinas\" href=\"https:\/\/www.ozono21.com\/blog\/toxinas\/sistemas-pasivos-de-seguridad-alimentaria-en-cocinas\/\" target=\"_blank\" rel=\"noopener noreferrer\">Sistemas pasivos de seguridad alimentaria en cocinas<\/a><\/strong><\/li>\n<li><strong><a title=\"Los restaurantes estadounidenses de McDonalds retiran el tomate de sus hamburguesas por precauci\u00f3n ante un brote de salmonelosis\" href=\"https:\/\/www.ozono21.com\/blog\/bacterias\/los-restaurantes-estadounidenses-de-mcdonalds-retiran-el-tomate-de-sus-hamburguesas-por-precaucion-ante-un-brote-de-salmonelosis\/\" target=\"_blank\" rel=\"noopener noreferrer\">Los restaurantes estadounidenses de McDonalds retiran el tomate de sus hamburguesas por precauci\u00f3n ante un brote de salmonelosis<\/a><\/strong><\/li>\n<li><strong><a title=\"La ley obliga a los restaurantes de comida r\u00e1pida de Nueva York a especificar sus calor\u00edas\" href=\"https:\/\/www.ozono21.com\/blog\/salud\/la-ley-obliga-a-los-restaurantes-de-comida-rapida-de-nueva-york-a-especificar-sus-calorias\/\" target=\"_blank\" rel=\"noopener noreferrer\">La ley obliga a los restaurantes de comida r\u00e1pida de Nueva York a especificar sus calor\u00edas<\/a><\/strong><\/li>\n<li><strong><a title=\"Comida Preparada\" href=\"https:\/\/www.ozono21.com\/blog\/salud\/manipulacion-correcta-de-comida-preparada\/\" target=\"_blank\" rel=\"noopener noreferrer\">Manipulaci\u00f3n correcta de comida preparada<\/a><\/strong><\/li>\n<\/ul>\n<p><\/big><\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td bgcolor=\"#3b7cff\" height=\"25\" width=\"600\" align=\"center\"><strong><a title=\"Videos YouTube\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/user\/ozono21\/videos?sort=p&amp;view=0&amp;flow=grid\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" border=\"0\" alt=\"Videos Youtube\" width=\"600\" height=\"25\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Videos-Youtube.png\" \/><\/a><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" width=\"640\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/hy4FIfaUav0\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5195062\" class=\"pvc_stats total_only  \" data-element-id=\"5195062\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Se ha comprobado que este tipo de alimentos tienen m\u00e1s grasa y sal, adem\u00e1s de menos vitaminas. La mitad de los pa\u00edses europeos carece de normas para garantizar la disponibilidad de comida saludable en los restaurantes, comedores o para comer &hellip; <a href=\"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5195062\" class=\"pvc_stats total_only  \" data-element-id=\"5195062\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":5195063,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[9,28,11,7,4],"tags":[24,71,21],"class_list":["post-5195062","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-alimentos","category-frutas-y-verduras","category-higiene","category-salud","category-toxinas","tag-alimentos-2","tag-higiene","tag-salud-2"],"a3_pvc":{"activated":true,"total_views":4065,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>COMIDA saludable fuera de CASA<\/title>\n<meta name=\"description\" content=\"Comida saludable es imprescindible para nuestra salud. La mitad de pa\u00edses europeos sin normas para garantizar comida saludable fuera de casa\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"COMIDA saludable fuera de CASA\" \/>\n<meta property=\"og:description\" content=\"Comida saludable es imprescindible para nuestra salud. La mitad de pa\u00edses europeos sin normas para garantizar comida saludable fuera de casa\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/\" \/>\n<meta property=\"og:site_name\" content=\"- Blog Ozono21\" \/>\n<meta property=\"article:published_time\" content=\"2012-04-21T13:01:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-22T17:43:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/04\/vida-sana-comida-basura-e1455791435713.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"531\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"INVESTIGACION Ozono21\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"INVESTIGACION Ozono21\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/comida-saludable-fuera-de-casa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/comida-saludable-fuera-de-casa\\\/\"},\"author\":{\"name\":\"INVESTIGACION Ozono21\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\"},\"headline\":\"La mitad de los pa\u00edses europeos carece de normas para garantizar comida saludable fuera de casa\",\"datePublished\":\"2012-04-21T13:01:56+00:00\",\"dateModified\":\"2026-01-22T17:43:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/comida-saludable-fuera-de-casa\\\/\"},\"wordCount\":541,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/comida-saludable-fuera-de-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/04\\\/vida-sana-comida-basura-e1455791435713.jpg\",\"keywords\":[\"Alimentos\",\"Higiene\",\"Salud\"],\"articleSection\":[\"Alimentos\",\"Frutas y Verduras\",\"Higiene\",\"Salud\",\"Toxinas\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/comida-saludable-fuera-de-casa\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/comida-saludable-fuera-de-casa\\\/\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/comida-saludable-fuera-de-casa\\\/\",\"name\":\"COMIDA saludable fuera de CASA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/comida-saludable-fuera-de-casa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/comida-saludable-fuera-de-casa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/04\\\/vida-sana-comida-basura-e1455791435713.jpg\",\"datePublished\":\"2012-04-21T13:01:56+00:00\",\"dateModified\":\"2026-01-22T17:43:41+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\"},\"description\":\"Comida saludable es imprescindible para nuestra salud. La mitad de pa\u00edses europeos sin normas para garantizar comida saludable fuera de casa\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/comida-saludable-fuera-de-casa\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/comida-saludable-fuera-de-casa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/comida-saludable-fuera-de-casa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/04\\\/vida-sana-comida-basura-e1455791435713.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/04\\\/vida-sana-comida-basura-e1455791435713.jpg\",\"width\":750,\"height\":531},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/toxinas\\\/comida-saludable-fuera-de-casa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La mitad de los pa\u00edses europeos carece de normas para garantizar comida saludable fuera de casa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\",\"name\":\"Blog Ozono21\",\"description\":\" - Blog Ozono21\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\",\"name\":\"INVESTIGACION Ozono21\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"caption\":\"INVESTIGACION Ozono21\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"COMIDA saludable fuera de CASA","description":"Comida saludable es imprescindible para nuestra salud. La mitad de pa\u00edses europeos sin normas para garantizar comida saludable fuera de casa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/","og_locale":"es_ES","og_type":"article","og_title":"COMIDA saludable fuera de CASA","og_description":"Comida saludable es imprescindible para nuestra salud. La mitad de pa\u00edses europeos sin normas para garantizar comida saludable fuera de casa","og_url":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/","og_site_name":"- Blog Ozono21","article_published_time":"2012-04-21T13:01:56+00:00","article_modified_time":"2026-01-22T17:43:41+00:00","og_image":[{"width":750,"height":531,"url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/04\/vida-sana-comida-basura-e1455791435713.jpg","type":"image\/jpeg"}],"author":"INVESTIGACION Ozono21","twitter_misc":{"Escrito por":"INVESTIGACION Ozono21","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/#article","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/"},"author":{"name":"INVESTIGACION Ozono21","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12"},"headline":"La mitad de los pa\u00edses europeos carece de normas para garantizar comida saludable fuera de casa","datePublished":"2012-04-21T13:01:56+00:00","dateModified":"2026-01-22T17:43:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/"},"wordCount":541,"commentCount":0,"image":{"@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/04\/vida-sana-comida-basura-e1455791435713.jpg","keywords":["Alimentos","Higiene","Salud"],"articleSection":["Alimentos","Frutas y Verduras","Higiene","Salud","Toxinas"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/","url":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/","name":"COMIDA saludable fuera de CASA","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/#primaryimage"},"image":{"@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/04\/vida-sana-comida-basura-e1455791435713.jpg","datePublished":"2012-04-21T13:01:56+00:00","dateModified":"2026-01-22T17:43:41+00:00","author":{"@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12"},"description":"Comida saludable es imprescindible para nuestra salud. La mitad de pa\u00edses europeos sin normas para garantizar comida saludable fuera de casa","breadcrumb":{"@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/#primaryimage","url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/04\/vida-sana-comida-basura-e1455791435713.jpg","contentUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/04\/vida-sana-comida-basura-e1455791435713.jpg","width":750,"height":531},{"@type":"BreadcrumbList","@id":"https:\/\/www.ozono21.com\/blog\/toxinas\/comida-saludable-fuera-de-casa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ozono21.com\/blog\/"},{"@type":"ListItem","position":2,"name":"La mitad de los pa\u00edses europeos carece de normas para garantizar comida saludable fuera de casa"}]},{"@type":"WebSite","@id":"https:\/\/www.ozono21.com\/blog\/#website","url":"https:\/\/www.ozono21.com\/blog\/","name":"Blog Ozono21","description":" - Blog Ozono21","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ozono21.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12","name":"INVESTIGACION Ozono21","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","caption":"INVESTIGACION Ozono21"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/04\/vida-sana-comida-basura-e1455791435713.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5195062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/comments?post=5195062"}],"version-history":[{"count":0,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5195062\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media\/5195063"}],"wp:attachment":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media?parent=5195062"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/categories?post=5195062"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/tags?post=5195062"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}