{"id":5194290,"date":"2012-01-05T20:20:58","date_gmt":"2012-01-05T18:20:58","guid":{"rendered":"https:\/\/www.ozono21.com\/blog\/?p=5194290"},"modified":"2026-01-23T15:59:51","modified_gmt":"2026-01-23T13:59:51","slug":"%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos","status":"publish","type":"post","link":"https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/","title":{"rendered":"\u00bfSe acaba el mundo tal y como lo conocemos?"},"content":{"rendered":"<p style=\"text-align: justify;\">\n<h2 style=\"text-align: justify;\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-thumbnail wp-image-5194291\" style=\"margin: 20px 5px 20px 0px; cursor: hand; border: 0px;\" title=\"Gasolina\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/01\/gasolina-150x150.jpg\" alt=\" mundo \" width=\"140\" height=\"212\" \/><a title=\"Ozono21\" href=\"https:\/\/www.ozono21.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Uhh\u2026 hoy vamos a ponernos agoreros o cenizos. \u00bfLlega el ocaso? \u00bfSe acaba el mundo tal y como lo conocemos? <\/strong>\u00bfLos recursos del planeta llegan ya a su fin?.Tal vez.<\/a><\/strong><\/h2>\n<\/p>\n<p style=\"text-align: justify;\"><strong><a title=\"Ozono21\" href=\"https:\/\/www.ozono21.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">El problema es que con estas predicciones pasa un poco lo mismo que con las predicciones mayas o las que formulan hombres en t\u00fanica a las cuatro de la ma\u00f1ana: no dan ni una. As\u00ed que uno empieza a desconfiar. S\u00ed, puede ser que ahora s\u00ed lo acierten\u2026 pero \u00bfno se pens\u00f3 eso mismo antes?<\/a><\/strong><\/p>\n<p>Fuente: xatakaciencia.com (13 sep. 2011)<\/p>\n<p style=\"text-align: justify;\">Por ejemplo, <strong>veamos el tema de la inminente escasez del petr\u00f3leo<\/strong>. Seguro que m\u00e1s de uno de vosotros, que a\u00fan ten\u00e9is que pagar 4 o 5 a\u00f1os de vuestro coche de gasolina, habr\u00e9is pensado\u2026 \u2018si lo llego a saber, me espero a un h\u00edbrido o uno el\u00e9ctrico`. Sin embargo, todo el siglo XX parece haber sido una continua se\u00f1al de alarma sobre la escasez de petr\u00f3leo. <\/p>\n<p style=\"text-align: justify;\">En 1914, el Departamento de Minas de EEUU predijo que <strong>las reservas del pa\u00eds durar\u00edan 10 a\u00f1os<\/strong>, no m\u00e1s. En 1939, el Departamento del Interior predijo que el petr\u00f3leo no durar\u00eda m\u00e1s de 13 a\u00f1os. 12 a\u00f1os despu\u00e9s, se volvi\u00f3 a poner la cifra de 13 a\u00f1os m\u00e1s. El presidente estadounidense <strong>Jimmy Carter<\/strong> anunci\u00f3 en la d\u00e9cada de 1970 que acabar\u00edamos con todas las reservas comprobadas de petr\u00f3leo del mundo en la pr\u00f3xima d\u00e9cada. <\/p>\n<p style=\"text-align: justify;\">A este respecto, <strong>Matt Ridley<\/strong>, de la Universidad de Oxford, se\u00f1ala:<\/p>\n<p style=\"text-align: justify;\">En 1970, hab\u00eda una reserva de 550 millardos de barriles de petr\u00f3leo en el mundo, y entre 1970 y 1990, el mundo utiliz\u00f3 600 millardos de barriles de petr\u00f3leo. As\u00ed que debimos rebasar el l\u00edmte de las reservas de 50 millardos de barriles para 1990. En realidad, ese a\u00f1o las reservas sin explotar llegaban a los 900 millardos de barriles, sin contar las arenas de alquitr\u00e1n de Athabasca en Alberta, las del Orinoco en Venezuela y las de las Monta\u00f1as Rocosas, que entre ellas contienen unos seis billones m\u00e9tricos de barriles de petr\u00f3leo crudo pesado, o 20 veces m\u00e1s que las reservas comprobadas de Arabia Saud\u00ed. La explotaci\u00f3n de estas reservas de petr\u00f3leo pesado es costosa, pero es posible que el refinamiento bacterial pronto las haga competitivas con el petr\u00f3leo convencional incluso en los precios \u201cnormales\u201d. <\/p>\n<p style=\"text-align: justify;\">Los avisos sobre la escasez inminente de recursos tambi\u00e9n se han dado en el gas natural, por ejemplo, pero gracias a los recientes hallazgos de gas de pizarra, <strong>se han duplicado los recursos de EEUU<\/strong>, que ahora son suficientes para tres siglos. <\/p>\n<p style=\"text-align: justify;\">La tesis de Ridley es que, a pesar de que estos recursos son finitos, a\u00fan quedan d\u00e9cadas o incluso siglos para que se agoten. Y para entonces, <strong>se habr\u00e1n encontrado alternativas eficientes<\/strong>. <\/p>\n<p style=\"text-align: justify;\">Aunque quiz\u00e1 ahora s\u00ed que aciertan\u2026 \u00bfcre\u00e9is que hay motivo de alarma<\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td align=\"center\" bgcolor=\"#3b7cff\" width=\"600\" height=\"25\"><strong><a title=\"Acci\u00f3n del OZONO\" href=\"https:\/\/www.ozono21.com\/actualidad-interna\/accion-del-ozono\/423\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Noticias-Relacionadas.png\" alt=\"Noticias Relacionadas\" width=\"600\" height=\"25\" border=\"0\" \/><\/a><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><big><\/p>\n<ul>\n<li><strong><a title=\"El consumo absurdo y creciente es la amenaza clave para el planeta\" href=\"https:\/\/www.ozono21.com\/blog\/alimentos\/consumo-absurdo-la-amenaza-del-planeta\/\" target=\"_blank\" rel=\"noopener noreferrer\">El consumo absurdo y creciente es la amenaza clave para el planeta<\/a><\/strong><\/li>\n<li><strong><a title=\"Alimentos ECOLOGICOS son la mejor opci\u00f3n para la salud de las personas y del planeta\" href=\"https:\/\/www.ozono21.com\/blog\/salud\/alimentos-ecologicos-salud-y-planeta\/\" target=\"_blank\" rel=\"noopener noreferrer\">Alimentos ECOLOGICOS son la mejor opci\u00f3n para la salud de las personas y del planeta<\/a><\/strong><\/li>\n<\/ul>\n<p><\/big><\/p>\n<table border=\"3\" cellspacing=\"0\" cellpadding=\"0\">\n<tbody>\n<tr>\n<td align=\"center\" bgcolor=\"#3b7cff\" width=\"600\" height=\"25\"><strong><a title=\"Videos YouTube\" href=\"https:\/\/www.youtube.com\/user\/ozono21\/videos?sort=p&amp;view=0&amp;flow=grid\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2014\/06\/Videos-Youtube.png\" alt=\"Videos Youtube\" width=\"600\" height=\"25\" border=\"0\" \/><\/a><\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/P><\/p>\n<p style=\"text-align: center;\"><iframe loading=\"lazy\" width=\"632\" height=\"480\" src=\"https:\/\/www.youtube.com\/embed\/QdkDOKOOJIg\" frameborder=\"0\" allow=\"accelerometer; autoplay; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5194290\" class=\"pvc_stats total_only  \" data-element-id=\"5194290\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Uhh\u2026 hoy vamos a ponernos agoreros o cenizos. \u00bfLlega el ocaso? \u00bfSe acaba el mundo tal y como lo conocemos? \u00bfLos recursos del planeta llegan ya a su fin?.Tal vez. El problema es que con estas predicciones pasa un poco &hellip; <a href=\"https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n<div class=\"pvc_clear\"><\/div>\n<p id=\"pvc_stats_5194290\" class=\"pvc_stats total_only  \" data-element-id=\"5194290\" style=\"\"><i class=\"pvc-stats-icon small\" aria-hidden=\"true\"><svg aria-hidden=\"true\" focusable=\"false\" data-prefix=\"far\" data-icon=\"chart-bar\" role=\"img\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 512 512\" class=\"svg-inline--fa fa-chart-bar fa-w-16 fa-2x\"><path fill=\"currentColor\" d=\"M396.8 352h22.4c6.4 0 12.8-6.4 12.8-12.8V108.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v230.4c0 6.4 6.4 12.8 12.8 12.8zm-192 0h22.4c6.4 0 12.8-6.4 12.8-12.8V140.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v198.4c0 6.4 6.4 12.8 12.8 12.8zm96 0h22.4c6.4 0 12.8-6.4 12.8-12.8V204.8c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v134.4c0 6.4 6.4 12.8 12.8 12.8zM496 400H48V80c0-8.84-7.16-16-16-16H16C7.16 64 0 71.16 0 80v336c0 17.67 14.33 32 32 32h464c8.84 0 16-7.16 16-16v-16c0-8.84-7.16-16-16-16zm-387.2-48h22.4c6.4 0 12.8-6.4 12.8-12.8v-70.4c0-6.4-6.4-12.8-12.8-12.8h-22.4c-6.4 0-12.8 6.4-12.8 12.8v70.4c0 6.4 6.4 12.8 12.8 12.8z\" class=\"\"><\/path><\/svg><\/i> <img loading=\"lazy\" decoding=\"async\" width=\"16\" height=\"16\" alt=\"Loading\" src=\"https:\/\/www.ozono21.com\/blog\/wp-content\/plugins\/page-views-count\/ajax-loader-2x.gif\" border=0 \/><\/p>\n<div class=\"pvc_clear\"><\/div>\n","protected":false},"author":1,"featured_media":5194291,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[13,12],"tags":[74,77,72,73],"class_list":["post-5194290","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-medioambiente","category-polucion","tag-medioambiente","tag-ozono","tag-ozono21","tag-polucion"],"a3_pvc":{"activated":true,"total_views":4088,"today_views":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfSe acaba el mundo tal y como lo conocemos?<\/title>\n<meta name=\"description\" content=\".\u00bfSe acaba el mundo tal y como lo conocemos? \u00bfLlega el ocaso? \u00bfLos recursos del planeta llegan ya a su fin?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ozono21.com\/blog\/polucion\/\u00bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfSe acaba el mundo tal y como lo conocemos?\" \/>\n<meta property=\"og:description\" content=\".\u00bfSe acaba el mundo tal y como lo conocemos? \u00bfLlega el ocaso? \u00bfLos recursos del planeta llegan ya a su fin?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ozono21.com\/blog\/polucion\/\u00bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/\" \/>\n<meta property=\"og:site_name\" content=\"- Blog Ozono21\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-05T18:20:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-23T13:59:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/01\/gasolina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"529\" \/>\n\t<meta property=\"og:image:height\" content=\"397\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"INVESTIGACION Ozono21\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"INVESTIGACION Ozono21\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/polucion\\\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/polucion\\\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\\\/\"},\"author\":{\"name\":\"INVESTIGACION Ozono21\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\"},\"headline\":\"\u00bfSe acaba el mundo tal y como lo conocemos?\",\"datePublished\":\"2012-01-05T18:20:58+00:00\",\"dateModified\":\"2026-01-23T13:59:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/polucion\\\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\\\/\"},\"wordCount\":531,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/polucion\\\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/gasolina.jpg\",\"keywords\":[\"MedioAmbiente\",\"OZONO\",\"Ozono21\",\"Poluci\u00f3n\"],\"articleSection\":[\"MedioAmbiente\",\"Poluci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/polucion\\\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/polucion\\\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\\\/\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/polucion\\\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\\\/\",\"name\":\"\u00bfSe acaba el mundo tal y como lo conocemos?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/polucion\\\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/polucion\\\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/gasolina.jpg\",\"datePublished\":\"2012-01-05T18:20:58+00:00\",\"dateModified\":\"2026-01-23T13:59:51+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\"},\"description\":\".\u00bfSe acaba el mundo tal y como lo conocemos? \u00bfLlega el ocaso? \u00bfLos recursos del planeta llegan ya a su fin?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/polucion\\\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/polucion\\\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/polucion\\\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/gasolina.jpg\",\"contentUrl\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/wp-content\\\/uploads\\\/2012\\\/01\\\/gasolina.jpg\",\"width\":529,\"height\":397},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/polucion\\\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfSe acaba el mundo tal y como lo conocemos?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/\",\"name\":\"Blog Ozono21\",\"description\":\" - Blog Ozono21\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.ozono21.com\\\/blog\\\/#\\\/schema\\\/person\\\/16639932c214a173193498aee8204d12\",\"name\":\"INVESTIGACION Ozono21\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g\",\"caption\":\"INVESTIGACION Ozono21\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfSe acaba el mundo tal y como lo conocemos?","description":".\u00bfSe acaba el mundo tal y como lo conocemos? \u00bfLlega el ocaso? \u00bfLos recursos del planeta llegan ya a su fin?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ozono21.com\/blog\/polucion\/\u00bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfSe acaba el mundo tal y como lo conocemos?","og_description":".\u00bfSe acaba el mundo tal y como lo conocemos? \u00bfLlega el ocaso? \u00bfLos recursos del planeta llegan ya a su fin?","og_url":"https:\/\/www.ozono21.com\/blog\/polucion\/\u00bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/","og_site_name":"- Blog Ozono21","article_published_time":"2012-01-05T18:20:58+00:00","article_modified_time":"2026-01-23T13:59:51+00:00","og_image":[{"width":529,"height":397,"url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/01\/gasolina.jpg","type":"image\/jpeg"}],"author":"INVESTIGACION Ozono21","twitter_misc":{"Escrito por":"INVESTIGACION Ozono21","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/#article","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/"},"author":{"name":"INVESTIGACION Ozono21","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12"},"headline":"\u00bfSe acaba el mundo tal y como lo conocemos?","datePublished":"2012-01-05T18:20:58+00:00","dateModified":"2026-01-23T13:59:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/"},"wordCount":531,"commentCount":0,"image":{"@id":"https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/01\/gasolina.jpg","keywords":["MedioAmbiente","OZONO","Ozono21","Poluci\u00f3n"],"articleSection":["MedioAmbiente","Poluci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/","url":"https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/","name":"\u00bfSe acaba el mundo tal y como lo conocemos?","isPartOf":{"@id":"https:\/\/www.ozono21.com\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/#primaryimage"},"image":{"@id":"https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/01\/gasolina.jpg","datePublished":"2012-01-05T18:20:58+00:00","dateModified":"2026-01-23T13:59:51+00:00","author":{"@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12"},"description":".\u00bfSe acaba el mundo tal y como lo conocemos? \u00bfLlega el ocaso? \u00bfLos recursos del planeta llegan ya a su fin?","breadcrumb":{"@id":"https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/#primaryimage","url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/01\/gasolina.jpg","contentUrl":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/01\/gasolina.jpg","width":529,"height":397},{"@type":"BreadcrumbList","@id":"https:\/\/www.ozono21.com\/blog\/polucion\/%c2%bfse-acaba-el-mundo-tal-y-como-lo-conocemos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.ozono21.com\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00bfSe acaba el mundo tal y como lo conocemos?"}]},{"@type":"WebSite","@id":"https:\/\/www.ozono21.com\/blog\/#website","url":"https:\/\/www.ozono21.com\/blog\/","name":"Blog Ozono21","description":" - Blog Ozono21","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ozono21.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.ozono21.com\/blog\/#\/schema\/person\/16639932c214a173193498aee8204d12","name":"INVESTIGACION Ozono21","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f00ed9ac57a3eea6b9830d73dc9f9214775648c7763edcb20475eb83509b31fd?s=96&d=mm&r=g","caption":"INVESTIGACION Ozono21"}}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/www.ozono21.com\/blog\/wp-content\/uploads\/2012\/01\/gasolina.jpg","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5194290","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/comments?post=5194290"}],"version-history":[{"count":0,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/posts\/5194290\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media\/5194291"}],"wp:attachment":[{"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/media?parent=5194290"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/categories?post=5194290"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ozono21.com\/blog\/wp-json\/wp\/v2\/tags?post=5194290"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}